{"id":2197,"date":"2020-09-22T17:30:04","date_gmt":"2020-09-22T17:30:04","guid":{"rendered":"http:\/\/trucos.com\/uncategorized\/como-ver-un-directo-en-facebook\/"},"modified":"2020-09-22T17:30:04","modified_gmt":"2020-09-22T17:30:04","slug":"com-veure-un-directe-a-facebook","status":"publish","type":"post","link":"https:\/\/trucos.com\/ca\/internet\/com-veure-un-directe-a-facebook\/","title":{"rendered":"Com veure un directe a Facebook"},"content":{"rendered":"<p>Tot seguit t&#039;ensenyarem tot el que has de saber sobre els <strong>v\u00eddeos en directe de <a href=\"http:\/\/trucos.com\/ca\/internet\/com-posar-facebook-en-mode-fosc\/\">Facebook<\/a><\/strong>, des de veure qualsevol streaming que s&#039;estigui emetent a crear les teves pr\u00f2pies retransmissions en directe gr\u00e0cies a <strong>Facebook Live<\/strong>, l&#039;eina de directes de la popular <a href=\"http:\/\/trucos.com\/ca\/internet\/com-pujar-un-pdf-a-facebook\/\">xarxa social<\/a>. I \u00e9s que les emissions en directe s&#039;han convertit en tot un fenomen en xarxes socials i cada cop apareixen m\u00e9s aplicacions que permeten tant <strong>retransmetre mitjan\u00e7ant uns simples passos<\/strong> o <strong>gaudir de qualsevol <a href=\"http:\/\/trucos.com\/ca\/internet\/com-descarregar-skype-gratis-a-lordinador-i-el-mobil\/\">v\u00eddeo en directe<\/a><\/strong> que s&#039;estigui emetent des de qualsevol rac\u00f3 del m\u00f3n, tot aix\u00f2 a l&#039;abast d&#039;uns quants passos. No et perdis la nostra guia sobre <strong>com veure un directe de <a href=\"https:\/\/www.facebook.com\/\">Facebook<\/a><\/strong>, a m\u00e9s d&#039;aprendre a <strong>realitzar els teus propis streams<\/strong> en uns quants passos.<\/p>\n<div class=\"lyte-wrapper fourthree\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_kT2iloxin_Q\"><div id=\"lyte_kT2iloxin_Q\" data-src=\"\/\/i.ytimg.com\/vi\/kT2iloxin_Q\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/kT2iloxin_Q\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/kT2iloxin_Q\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/p>\n<h2>Com veure un v\u00eddeo en directe a Facebook<\/h2>\n<h3>\u00cdndex de continguts<\/h3>\n<ul>\n<li><a href=\"#que es\">Qu\u00e8 \u00e9s un streaming?<\/a><\/li>\n<li><a href=\"#fb live\">Qu\u00e8 \u00e9s Facebook Live?<\/a><\/li>\n<li><a href=\"#como usar\">Com utilitzar Facebook Live?<\/a><\/li>\n<li><a href=\"#como ver\">Com veure v\u00eddeos en directe de Facebook Live?<\/a><\/li>\n<\/ul>\n<p>Gr\u00e0cies a la nostra guia sobre les <strong>retransmissions en directe<\/strong> relacionades amb <strong>Facebook<\/strong>, aprendr\u00e0s tot el que has de saber sobre <strong>Facebook Live<\/strong>&nbsp;(V\u00eddeos en directe) i comen\u00e7ar a retransmetre els teus propis directes d&#039;una manera senzilla i directa.<\/p>\n<h2><a name=\"que es\"><span style=\"color:#000000\">Qu\u00e8 \u00e9s un streaming?<\/span><\/a><\/h2>\n<p>El streaming \u00e9s la paraula en angl\u00e8s que defineix la possibilitat de <strong>veure un v\u00eddeo a trav\u00e9s d&#039;internet<\/strong> sense haver de descarregar-lo, \u00e9s a dir, nom\u00e9s a trav\u00e9s de la transmissi\u00f3 de dades, en aquest cas, de v\u00eddeo i \u00e0udio per donar lloc a una retransmissi\u00f3 en viu. Per aix\u00f2, cal comptar amb una <strong>bona connexi\u00f3 a internet<\/strong>, ja sigui mitjan\u00e7ant <a href=\"http:\/\/trucos.com\/ca\/internet\/repetidor-wifi-com-es-fa-servir-i-els-seus-millors-trucs\/\">WiFi<\/a> o dades m\u00f2bils en el cas de dispositius t\u00e0ctils (smartphones o tablets) o port\u00e0tils, per gaudir d&#039;una retransmissi\u00f3 sense talls ia bona qualitat d&#039;imatge i so.<\/p>\n<h2><a id=\"fb live\" name=\"fb live\"><span style=\"color:#000000\">Qu\u00e8 \u00e9s Facebook Live?<\/span><\/a><\/h2>\n<p>Facebook Live \u00e9s la nova eina introdu\u00efda per Facebook per a la <strong>emissi\u00f3 de v\u00eddeos en directe<\/strong>, aix\u00ed com la possibilitat de veure v\u00eddeos en directe d&#039;altres persones que retransmeten des de qualsevol part del m\u00f3n. Aix\u00ed, i nom\u00e9s mitjan\u00e7ant un m\u00f2bil o mitjan\u00e7ant un ordinador, \u00e9s possible connectar amb qualsevol v\u00eddeo en directe i veure quins continguts ofereix qualsevol altre usuari, com esdeveniments d&#039;inter\u00e8s de qualsevol tipus (esportiu, social, laboral, d&#039;oci, etc.) i reaccionar a aquests continguts amb <strong>M&#039;agrada<\/strong> o deixant <strong>comentaris<\/strong>.<\/p>\n<h2><a id=\"como usar\" name=\"como usar\"><span style=\"color:#000000\">Com utilitzar Facebook Live?<\/span><\/a><\/h2>\n<p>Per treure tot el potencial a Facebook Live i oferir retransmissions de qualitat \u00e9s recomanable fer servir un <strong><a href=\"http:\/\/trucos.com\/ca\/mobils\/com-saber-limei-del-teu-mobil-i-android\/\">m\u00f2bil<\/a> o tablet amb c\u00e0mera<\/strong>, ja que \u00e9s molt m\u00e9s c\u00f2mode i manejable que, per exemple, un ordinador port\u00e0til. Per accedir a Facebook Live i comen\u00e7ar a retransmetre tan sols has de pr\u00e9mer la icona <strong>En directe<\/strong> al costat d&#039;una c\u00e0mera de v\u00eddeo en vermell, just a sota de la caixa per compartir el teu estat <strong>Qu\u00e8 penses?<\/strong><\/p>\n<p><strong><img decoding=\"async\" alt=\"Com veure un directe a Facebook\" src=\"\/media\/upload\/2020\/09\/22\/como-ver-directo-facebook-01.jpg\" style=\"width:100%\" title=\"Com veure un directe a Facebook\" \/><\/strong><\/p>\n<p>En accedir a aquesta icona s&#039;activar\u00e0 la c\u00e0mera del dispositiu i podr\u00e0s accedir a les opcions seg\u00fcents:<\/p>\n<ul>\n<li><strong>Privadesa<\/strong> | Selecciona qui vols que pugui veure la teva retransmissi\u00f3 en directe. Per defecte apareix l&#039;opci\u00f3 P\u00fablic, de manera que qualsevol altre usuari de Facebook podr\u00e0 veure el teu v\u00eddeo en directe. Tot i que tamb\u00e9 \u00e9s possible restringir el seu acc\u00e9s a trav\u00e9s de les opcions Amics (nom\u00e9s disponible per a les teves amistats de Facebook), Solament jo o M\u00e9s, on podr\u00e0s triar a quin tipus de p\u00fablic et vols dirigir.<\/li>\n<li><strong>T\u00edtol<\/strong> | Escriu el t\u00edtol que vols posar a la teva retransmissi\u00f3 en directe; recomanem t\u00edtols cridaners i que tinguin a veure amb el contingut que emetis.<\/li>\n<li><strong>Canviar la c\u00e0mera<\/strong> | Aquesta opci\u00f3 et permet alternar entre la c\u00e0mera del darrere i la c\u00e0mera davantera del dispositiu, en cas que les tinguin.<\/li>\n<li><strong>Transmetre<\/strong> | Quan premeu aquest bot\u00f3, l&#039;emissi\u00f3 en directe s&#039;iniciar\u00e0; depenent de la privadesa escollida, les vostres amistats rebran la notificaci\u00f3 de la vostra arrencada d&#039;emissi\u00f3 en directe.<\/li>\n<\/ul>\n<p>Per\u00f2 encara hi ha m\u00e9s opcions per configurar l&#039;emissi\u00f3 en directe mitjan\u00e7ant diferents icones d&#039;acc\u00e9s directe repartides per la pantalla:<\/p>\n<ul>\n<li>A la cantonada superior esquerra de la pantalla se situa la icona per <strong>editar la imatge<\/strong>, per aplicar aix\u00ed diferents filtres a l&#039;emissi\u00f3 en directe; tant \u00e9s aix\u00ed que podem afegir diferents filtres de colors, aix\u00ed com afegir dibuixos a l&#039;emissi\u00f3 en directe.<\/li>\n<li>A la cantonada superior dreta se situa la icona per <strong>alternar entre la c\u00e0mera del darrere i la c\u00e0mera davantera<\/strong> a l&#039;instant.<\/li>\n<li>A la part inferior esquerra hi ha la icona <strong>+<\/strong> per convidar un amic de Facebook perqu\u00e8 vegi la retransmissi\u00f3, una opci\u00f3 interessant perqu\u00e8 nom\u00e9s vegin el teu directe determinats usuaris.<\/li>\n<li>Just al costat de la icona en forma de persona tenim l&#039;opci\u00f3 de <strong>escriure comentaris<\/strong>, per aix\u00ed interactuar amb altres usuaris que escriguin comentaris a la teva retransmissi\u00f3 en directe.<\/li>\n<li>A la part inferior se situa l&#039;opci\u00f3 de <strong>finalitzar la retransmissi\u00f3<\/strong> en directe. Quan finalitzis un directe, tindr\u00e0s les opci\u00f3 d&#039;eliminar-la o publicar-la al teu perfil de Facebook; si la publiques, qualsevol usuari podr\u00e0 accedir-hi per veure-la, depenent de la privadesa que tinguis configurada.<\/li>\n<\/ul>\n<p><img decoding=\"async\" alt=\"Com veure un directe a Facebook\" src=\"\/media\/upload\/2020\/09\/22\/como-ver-directo-facebook-02.jpg\" style=\"width:100%\" title=\"Com veure un directe a Facebook\" \/><\/p>\n<p>Recordeu que durant l&#039;emissi\u00f3 podreu veure quins usuaris estan com a espectadors, les seves reaccions (com els <strong>M&#039;agrada<\/strong>, <strong>M&#039;Encanta<\/strong> flotant per la pantalla) i els <strong>comentaris<\/strong> que van deixant a la part inferior de la pantalla.<\/p>\n<h2><a id=\"como ver\" name=\"como ver\"><span style=\"color:#000000\">Com veure v\u00eddeos en directe de Facebook Live?<\/span><\/a><\/h2>\n<p>A m\u00e9s de fer els teus propis streamings, tamb\u00e9 pots <strong>gaudir d&#039;una \u00e0mplia selecci\u00f3 de directes<\/strong> compartits per molts altres usuaris de Facebook arreu del m\u00f3n, streamings disponibles a trav\u00e9s de Facebook Live.<\/p>\n<p><img decoding=\"async\" alt=\"Com veure un directe a Facebook\" src=\"\/media\/upload\/2020\/09\/22\/como-ver-directo-facebook-03.jpg\" style=\"width:100%\" title=\"Com veure un directe a Facebook\" \/><\/p>\n<p>A Facebook Live s&#039;accedeix a trav\u00e9s de la columna lateral de l&#039;esquerra de la pantalla, a la secci\u00f3 d&#039;aplicacions sota el nom de <strong>V\u00eddeo en directe<\/strong>; en pr\u00e9mer accedir\u00e0s a una selecci\u00f3 de directes relacionats amb els teus gustos i amistats, a m\u00e9s d&#039;altres streamings que Facebook pot considerar del teu inter\u00e8s. Si vols accedir a qualsevol d&#039;aquests v\u00eddeos nom\u00e9s has de <strong>pr\u00e9mer sobre la retransmissi\u00f3<\/strong> i comen\u00e7ar a gaudir dels teus directes preferits.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=SZdZx7MieWc\"><img decoding=\"async\" alt=\"Com veure un directe a Facebook\" src=\"\/media\/upload\/2020\/09\/22\/como-ver-directo-facebook-04.jpg\" style=\"width:100%\" title=\"Com veure un directe a Facebook\" \/><\/a><\/p>\n<h2>M\u00e9s trucs sobre Facebook<\/h2>\n<ul>\n<li><a href=\"http:\/\/trucos.com\/ca\/internet\/com-pujar-un-pdf-a-facebook\/\">Com pujar un PDF a Facebook<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/ca\/internet\/com-etiquetar-a-facebook\/\">Com etiquetar a Facebook<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/ca\/internet\/com-desbloquejar-algu-a-facebook\/\">Com desbloquejar alg\u00fa a Facebook<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/ca\/internet\/com-posar-facebook-en-mode-fosc\/\">Com posar Facebook en mode fosc<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8n a veure streamings en directe amb Facebook Live i crea els teus propis directes gr\u00e0cies al nostre tutorial<\/p>","protected":false},"author":2,"featured_media":2198,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[19],"class_list":["post-2197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet","tag-tecnologia"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo ver un directo en Facebook - Trucos.com<\/title>\n<meta name=\"description\" content=\"Aprende a ver streamings en directo con Facebook Live y crea tus propios directos gracias a nuestro tutorial\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trucos.com\/ca\/internet\/com-veure-un-directe-a-facebook\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo ver un directo en Facebook - Trucos.com\" \/>\n<meta property=\"og:description\" content=\"Aprende a ver streamings en directo con Facebook Live y crea tus propios directos gracias a nuestro tutorial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trucos.com\/ca\/internet\/com-veure-un-directe-a-facebook\/\" \/>\n<meta property=\"og:site_name\" content=\"Trucos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trucoscom\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T17:30:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_ver_directo__facebook.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuts\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com veure un directe a Facebook - Trucos.com","description":"Apr\u00e8n a veure streamings en directe amb Facebook Live i crea els teus propis directes gr\u00e0cies al nostre tutorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trucos.com\/ca\/internet\/com-veure-un-directe-a-facebook\/","og_locale":"ca_ES","og_type":"article","og_title":"C\u00f3mo ver un directo en Facebook - Trucos.com","og_description":"Aprende a ver streamings en directo con Facebook Live y crea tus propios directos gracias a nuestro tutorial","og_url":"https:\/\/trucos.com\/ca\/internet\/com-veure-un-directe-a-facebook\/","og_site_name":"Trucos.com","article_publisher":"https:\/\/www.facebook.com\/trucoscom\/","article_published_time":"2020-09-22T17:30:04+00:00","og_image":[{"width":600,"height":412,"url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_ver_directo__facebook.jpg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Redaccion","Temps estimat de lectura":"6 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/#article","isPartOf":{"@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/"},"author":{"name":"Redaccion","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536"},"headline":"C\u00f3mo ver un directo en Facebook","datePublished":"2020-09-22T17:30:04+00:00","mainEntityOfPage":{"@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/"},"wordCount":1270,"publisher":{"@id":"https:\/\/trucos.com\/#organization"},"image":{"@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_ver_directo__facebook.jpg","keywords":["Tecnologia"],"articleSection":["Internet"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/","url":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/","name":"Com veure un directe a Facebook - Trucos.com","isPartOf":{"@id":"https:\/\/trucos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/#primaryimage"},"image":{"@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_ver_directo__facebook.jpg","datePublished":"2020-09-22T17:30:04+00:00","description":"Apr\u00e8n a veure streamings en directe amb Facebook Live i crea els teus propis directes gr\u00e0cies al nostre tutorial","breadcrumb":{"@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/#primaryimage","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_ver_directo__facebook.jpg","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_ver_directo__facebook.jpg","width":600,"height":412},{"@type":"BreadcrumbList","@id":"https:\/\/trucos.com\/en\/internet\/how-to-see-a-live-on-facebook\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trucos.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo ver un directo en Facebook"}]},{"@type":"WebSite","@id":"https:\/\/trucos.com\/#website","url":"https:\/\/trucos.com\/","name":"Trucos.com","description":"Els millors trucs sobre videojocs, tecnologia i m\u00f2bils","publisher":{"@id":"https:\/\/trucos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trucos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/trucos.com\/#organization","name":"Trucos.com","url":"https:\/\/trucos.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","width":207,"height":68,"caption":"Trucos.com"},"image":{"@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trucoscom\/"]},{"@type":"Person","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","caption":"Redaccion"},"sameAs":["http:\/\/trucos.com"],"url":"https:\/\/trucos.com\/ca\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/posts\/2197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/comments?post=2197"}],"version-history":[{"count":0,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/posts\/2197\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/media\/2198"}],"wp:attachment":[{"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/media?parent=2197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/categories?post=2197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/tags?post=2197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}