{"id":348,"date":"2016-05-26T16:19:17","date_gmt":"2016-05-26T16:19:17","guid":{"rendered":"http:\/\/trucos.com\/uncategorized\/trucos-uncharted-4-para-ps4\/"},"modified":"2016-05-26T16:19:17","modified_gmt":"2016-05-26T16:19:17","slug":"trucs-uncharted-4-per-a-ps4","status":"publish","type":"post","link":"https:\/\/trucos.com\/ca\/videojocs\/trucs-uncharted-4-per-a-ps4\/","title":{"rendered":"Trucs Uncharted 4 per a PS4"},"content":{"rendered":"<p>T&#039;ajudem perqu\u00e8 aconsegueixis treure-li el m\u00e0xim partit a <a href=\"http:\/\/www.unchartedthegame.com\/es-es\/\" title=\"P\u00e0gina Oficial Uncharted 4\">Uncharted 4<\/a>.<\/p>\n<h2>Activar Trucs Uncharted 4<\/h2>\n<p>Un cop ens haguem passat el joc per primera vegada, al men\u00fa ens apareixer\u00e0 un nou apartat <strong>Extres,&nbsp;<\/strong>des d&#039;aquest men\u00fa amb els punts acumulats, podem desbloquejar <strong>aparences, armes, filtres i modificadors de joc<\/strong>&nbsp;que faran que les nostres seg\u00fcents partides guanyin al\u00b7licients. Us deixem un v\u00eddeo explicatiu amb l&#039;apartat Extras.<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"Com activar TOTS els TRUCS a Uncharted 4 El Desenlla\u00e7 del Lladre\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_Dd-C9l8sbto\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/Dd-C9l8sbto\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/Dd-C9l8sbto\" \/><meta itemprop=\"duration\" content=\"PT13M46S\" \/><meta itemprop=\"uploadDate\" content=\"2016-05-19T21:45:06Z\" \/><\/div><div id=\"lyte_Dd-C9l8sbto\" data-src=\"https:\/\/i.ytimg.com\/vi\/Dd-C9l8sbto\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Com activar TOTS els TRUCS a Uncharted 4 El Desenlla\u00e7 del Lladre<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/Dd-C9l8sbto\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/Dd-C9l8sbto\/0.jpg\" alt=\"Com activar TOTS els TRUCS a Uncharted 4 El Desenlla\u00e7 del Lladre\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Like si os ha gustado ;)\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<h2>Trofeu &quot;El Do de la Paraula&quot;<\/h2>\n<p>Aquest trofeu ho aconseguim despr\u00e9s de col\u00b7leccionar totes les converses opcionals, en total <strong>en tenim 36. <\/strong>Us deixem un v\u00eddeo per localitzar-les f\u00e0cilment, la primera no la trobem fins al cap\u00edtol 3.<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"Uncharted 4 | Localitzaci\u00f3 de les converses opcionals (Trofeu: El do de la paraula)\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_rIeSXhqdDKU\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/rIeSXhqdDKU\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/rIeSXhqdDKU\" \/><meta itemprop=\"duration\" content=\"PT16M15S\" \/><meta itemprop=\"uploadDate\" content=\"2016-05-09T08:32:00Z\" \/><\/div><div id=\"lyte_rIeSXhqdDKU\" data-src=\"https:\/\/i.ytimg.com\/vi\/rIeSXhqdDKU\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Uncharted 4 | Localitzaci\u00f3 de les converses opcionals (Trofeu: El do de la paraula)<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/rIeSXhqdDKU\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/rIeSXhqdDKU\/0.jpg\" alt=\"Uncharted 4 | Localitzaci\u00f3 de les converses opcionals (Trofeu: El do de la paraula)\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Hola muy buenas a todos, bienvenidos a este v\u00eddeo en el que ense\u00f1ar\u00e9 la localizaci\u00f3n de todas las conversaciones opcionales que debemos tener en Uncharted 4: El desenlace del ladr\u00f3n. En caso de no recoger alg\u00fan coleccionable podremos repetir cualquier cap\u00edtulo en cualquier dificultad y salir de \u00e9l nada m\u00e1s recoger el coleccionable. Al escuchar todas las conversaciones opcionales conseguiremos el trofeo El don de la palabra. El don de la palabra Escucha todas las conversaciones opcionales del juego. Gift of Gab Listen to all optional conversations in game Cap\u00edtulo 3 Conversaciones opcionales 1 y 2 Cap\u00edtulo 6 0:33 Conversaci\u00f3n opcional 1 0:52 Conversaci\u00f3n opcional 2 1:20 Conversaci\u00f3n opcional 3 Cap\u00edtulo 8 1:35 Conversaci\u00f3n opcional 1 1:57 Conversaci\u00f3n opcional 2 Cap\u00edtulo 9 2:05 Conversaci\u00f3n opcional 1 Cap\u00edtulo 10 2:33 Conversaciones opcionales 1 y 2 Cap\u00edtulo 11 3:39 Conversaci\u00f3n opcional 1 Cap\u00edtulo 12 4:14 Conversaci\u00f3n opcional 1 4:29 Conversaci\u00f3n opcional 2 Cap\u00edtulo 14 6:30 Conversaciones opcionales 1-4 8:37 Conversaci\u00f3n opcional 5 9:09 Conversaci\u00f3n opcional 6 Cap\u00edtulo 15 9:48 Conversaciones opcionales 1 y 2 Cap\u00edtulo 16 10:25 Conversaci\u00f3n opcional 1 10:52 Conversaciones opcionales 2 y 3 Cap\u00edtulo 17 11:43 Conversaciones opcionales 1 y 2 12:09 Conversaciones opcionales 3 y 4 12:54 Conversaciones opcionales 5 y 6 Cap\u00edtulo 18 13:38 Conversaciones opcionales 1 y 2 14:24 Conversaci\u00f3n opcional 3 14:45 Conversaci\u00f3n opcional 4 15:19 Conversaci\u00f3n opcional 5 Ep\u00edlogo 15:42 Conversaci\u00f3n opcional 1 Todas las gu\u00edas de Uncharted 4: El desenlace del ladr\u00f3n: https:\/\/www.youtube.com\/playlist?list=PLUEaSJ4rKZoJ7vUtjZ6xHz8WCFh2uCwT0 #Uncharted4 #Uncharted #Gu\u00edaDeTrofeos Suscr\u00edbete y activa la campana si quieres recibir un aviso cada vez que suba un v\u00eddeo: https:\/\/www.youtube.com\/subscription_center?add_user=GPAP360 ------ Redes sociales: Twitter: https:\/\/twitter.com\/_JavierParrado_ Facebook: https:\/\/www.facebook.com\/GuiasPasoAPaso360\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<h2>Trofeu &quot;L&#039;Art Perdut del Periodisme&quot;<\/h2>\n<p>Per aconseguir aquest trofeu cal recollir totes les entrades de diari, en total <strong>tenim 24<\/strong> i no recollim la primera fins al cap\u00edtol 8. Aqu\u00ed us deixem un v\u00eddeo per poder-les trobar totes.<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"Uncharted 4 | Localitzaci\u00f3 de les entrades del diari (Trofeu: L&#039;art perdut del periodisme +1)\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_8T2ThgN-oBg\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/8T2ThgN-oBg\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/8T2ThgN-oBg\" \/><meta itemprop=\"duration\" content=\"PT6M18S\" \/><meta itemprop=\"uploadDate\" content=\"2016-05-09T08:32:04Z\" \/><\/div><div id=\"lyte_8T2ThgN-oBg\" data-src=\"https:\/\/i.ytimg.com\/vi\/8T2ThgN-oBg\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Uncharted 4 | Localitzaci\u00f3 de les entrades del diari (Trofeu: L&#039;art perdut del periodisme +1)<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/8T2ThgN-oBg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/8T2ThgN-oBg\/0.jpg\" alt=\"Uncharted 4 | Localitzaci\u00f3 de les entrades del diari (Trofeu: L&#039;art perdut del periodisme +1)\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Hola muy buenas a todos, bienvenidos a este v\u00eddeo en el que ense\u00f1ar\u00e9 la localizaci\u00f3n de todas las Entradas del diario que debemos encontrar en Uncharted 4: El desenlace del ladr\u00f3n. En caso de no recoger alg\u00fan coleccionable podremos repetir cualquier cap\u00edtulo en cualquier dificultad y salir de \u00e9l nada m\u00e1s recoger el coleccionable. Al recoger todas las Entradas del diario conseguiremos un total de 2 trofeos. Anota esto Encuentra una entrada del diario. El arte perdido del periodismo Encuentra todas las entradas del diario. Jot This Down Find a Journal Entry Lost Art of Journaling Find all Journal Entries Cap\u00edtulo 8 0:11 Entrada del diario 1 0:29 Entrada del diario 2 Cap\u00edtulo 9 0:47 Entrada del diario 1 0:54 Entrada del diario 2 Cap\u00edtulo 10 1:03 Entrada del diario 1 1:20 Entrada del diario 2 1:35 Entrada del diario 3 1:45 Entrada del diario 4 Cap\u00edtulo 12 2:02 Entrada del diario 1 2:24 Entrada del diario 2 2:45 Entrada del diario 3 2:58 Entrada del diario 4 3:19 Entrada del diario 5 3:35 Entrada del diario 6 Cap\u00edtulo 13 3:50 Entrada del diario 1 4:04 Entrada del diario 2 Cap\u00edtulo 14 4:16 Entradas del diario 1 y 2 4:35 Entradas del diario 3 y 4 Cap\u00edtulo 15 5:17 Entrada del diario 1 Cap\u00edtulo 17 5:26 Entrada del diario 1 5:35 Entrada del diario 2 Cap\u00edtulo 18 5:48 Entrada del diario 1 6:00 Entrada del diario 2 Todas las gu\u00edas de Uncharted 4: El desenlace del ladr\u00f3n: https:\/\/www.youtube.com\/playlist?list=PLUEaSJ4rKZoJ7vUtjZ6xHz8WCFh2uCwT0 #Uncharted4 #Uncharted #Gu\u00edaDeTrofeos Suscr\u00edbete y activa la campana si quieres recibir un aviso cada vez que suba un v\u00eddeo: https:\/\/www.youtube.com\/subscription_center?add_user=GPAP360 ------ Redes sociales: Twitter: https:\/\/twitter.com\/_JavierParrado_ Facebook: https:\/\/www.facebook.com\/GuiasPasoAPaso360\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<h2>Trofeu &quot;Hist\u00f2ria Perduda&quot;<\/h2>\n<p>En aquest trofeu hem de trobar totes les notes de diari, fins al cap\u00edtol 8 no trobem la primera i hi ha diversos cap\u00edtols posteriors on tampoc trobarem notes. En total <strong>hi ha 23 notes<\/strong> que podem recollir. Us deixem un v\u00eddeo per poder-les localitzar totes.<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"Uncharted 4 | Localitzaci\u00f3 de les notes del diari (Trofeu: Hist\u00f2ria perduda +1)\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_iiASTiXNUII\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/iiASTiXNUII\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/iiASTiXNUII\" \/><meta itemprop=\"duration\" content=\"PT7M1S\" \/><meta itemprop=\"uploadDate\" content=\"2016-05-09T08:32:08Z\" \/><\/div><div id=\"lyte_iiASTiXNUII\" data-src=\"https:\/\/i.ytimg.com\/vi\/iiASTiXNUII\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Uncharted 4 | Localitzaci\u00f3 de les notes del diari (Trofeu: Hist\u00f2ria perduda +1)<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/iiASTiXNUII\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/iiASTiXNUII\/0.jpg\" alt=\"Uncharted 4 | Localitzaci\u00f3 de les notes del diari (Trofeu: Hist\u00f2ria perduda +1)\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Hola muy buenas a todos, bienvenidos a este v\u00eddeo en el que ense\u00f1ar\u00e9 la localizaci\u00f3n de todas las Notas del diario que debemos encontrar en Uncharted 4: El desenlace del ladr\u00f3n. En caso de no recoger alg\u00fan coleccionable podremos repetir cualquier cap\u00edtulo en cualquier dificultad y salir de \u00e9l nada m\u00e1s recoger el coleccionable. Al recoger todas las Notas del diario conseguiremos un total de 2 trofeos. Toma notas Encuentra una nota del diario. Historia perdida Encuentra todas las notas del diario. Take a Note Find a Journal Note Lost History Find All Journal Notes Cap\u00edtulo 8 0:11 Nota del diario 1 Cap\u00edtulo 9 0:27 Nota del diario 1 Cap\u00edtulo 10 0:44 Nota del diario 1 1:20 Nota del diario 2 Cap\u00edtulo 12 1:43 Nota del diario 1 2:12 Nota del diario 2 Cap\u00edtulo 13 2:32 Nota del diario 1 2:44 Nota del diario 2 Cap\u00edtulo 14 2:56 Nota del diario 1 3:19 Nota del diario 2 Cap\u00edtulo 15 3:30 Notas del diario 1-3 Cap\u00edtulo 17 4:42 Nota del diario 1 5:01 Nota del diario 2 Cap\u00edtulo 18 5:22 Nota del diario 1 5:33 Nota del diario 2 5:42 Nota del diario 3 5:57 Notas del diario 4 y 5 6:20 Nota del diario 6 Cap\u00edtulo 20 6:30 Nota del diario 1 Cap\u00edtulo 21 6:43 Nota del diario 1 Todas las gu\u00edas de Uncharted 4: El desenlace del ladr\u00f3n: https:\/\/www.youtube.com\/playlist?list=PLUEaSJ4rKZoJ7vUtjZ6xHz8WCFh2uCwT0 #Uncharted4 #Uncharted #Gu\u00edaDeTrofeos Suscr\u00edbete y activa la campana si quieres recibir un aviso cada vez que suba un v\u00eddeo: https:\/\/www.youtube.com\/subscription_center?add_user=GPAP360 ------ Redes sociales: Twitter: https:\/\/twitter.com\/_JavierParrado_ Facebook: https:\/\/www.facebook.com\/GuiasPasoAPaso360\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<h2>Trofeu &quot;Cazatesors Expert&quot;<\/h2>\n<p>Per aconseguir aquest trofeu hem de trobar tots els <strong>tresors ocults del joc<\/strong>. Hi ha a gaireb\u00e9 tots els cap\u00edtols, tret dels cap\u00edtols 1, 4, 5 i 7. A continuaci\u00f3 us deixem un v\u00eddeo per poder localitzar-los tots f\u00e0cilment i obtenir el Trofeu.<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"Uncharted 4 | Localitzaci\u00f3 dels tresors (Trofeu: Ca\u00e7atresors expert +2)\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_Cp5XfRNoz30\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/Cp5XfRNoz30\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/Cp5XfRNoz30\" \/><meta itemprop=\"duration\" content=\"PT32M43S\" \/><meta itemprop=\"uploadDate\" content=\"2016-05-09T08:31:56Z\" \/><\/div><div id=\"lyte_Cp5XfRNoz30\" data-src=\"https:\/\/i.ytimg.com\/vi\/Cp5XfRNoz30\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Uncharted 4 | Localitzaci\u00f3 dels tresors (Trofeu: Ca\u00e7atresors expert +2)<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/Cp5XfRNoz30\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/Cp5XfRNoz30\/0.jpg\" alt=\"Uncharted 4 | Localitzaci\u00f3 dels tresors (Trofeu: Ca\u00e7atresors expert +2)\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Hola muy buenas a todos, bienvenidos a este v\u00eddeo en el que ense\u00f1ar\u00e9 la localizaci\u00f3n de todos los tesoros que debemos encontrar en Uncharted 4: El desenlace del ladr\u00f3n. En caso de no recoger alg\u00fan coleccionable podremos repetir cualquier cap\u00edtulo en cualquier dificultad y salir de \u00e9l nada m\u00e1s recoger el coleccionable. Al recoger todos los tesoros conseguiremos un total de 3 trofeos. Primer tesoro Encuentra un tesoro. Cazatesoros Encuentra 50 tesoros. Cazatesoros experto Encuentra todos los tesoros. First Treasure Find a Treasure Treasure Hunter Find 50 treasures Treasure Master Find all Treasures Cap\u00edtulo 2 0:11 Tesoro 1 0:30 Tesoro 2 Cap\u00edtulo 3 0:43 Tesoro 1 1:01 Tesoro 2 1:18 Tesoro 3 1:38 Tesoro 4 Cap\u00edtulo 6 1:49 Tesoro 1 2:04 Tesoro 2 2:20 Tesoros 3 y 4 2:59 Tesoro 5 3:12 Tesoro 6 3:24 Tesoro 7 3:59 Tesoro 8 4:17 Tesoro 9 Cap\u00edtulo 8 4:33 Tesoro 1 4:56 Tesoro 2 5:12 Tesoro 3 5:27 Tesoro 4 5:50 Tesoro 5 6:06 Tesoro 6 6:22 Tesoro 7 6:34 Tesoro 8 6:53 Tesoro 9 7:08 Tesoro 10 7:30 Tesoro 11 Cap\u00edtulo 9 7:41 Tesoro 1 7:59 Tesoro 2 8:29 Tesoro 3 8:49 Tesoro 4 9:05 Tesoro 5 9:26 Tesoro 6 Cap\u00edtulo 10 9:38 Tesoro 1 10:00 Tesoro 2 10:33 Tesoro 3 10:58 Tesoro 4 11:17 Tesoro 5 11:40 Tesoro 6 12:05 Tesoro 7 12:38 Tesoro 8 13:05 Tesoro 9 13:22 Tesoro 10 13:47 Tesoro 11 14:13 Tesoro 12 14:32 Tesoro 13 14:44 Tesoros 14 y 15 Cap\u00edtulo 11 15:03 Tesoro 1 15:23 Tesoro 2 15:33 Tesoro 3 15:43 Tesoro 4 16:10 Tesoro 5 Cap\u00edtulo 12 16:21 Tesoro 1 16:52 Tesoro 2 17:12 Tesoros 3 y 4 17:45 Tesoro 5 18:06 Tesoro 6 18:36 Tesoro 7 18:54 Tesoro 8 19:05 Tesoro 9 19:16 Tesoro 10 19:34 Tesoro 11 20:08 Tesoro 12 20:31 Tesoro 13 Cap\u00edtulo 13 21:04 Tesoro 1 21:19 Tesoro 2 21:38 Tesoro 3 21:49 Tesoro 4 22:06 Tesoro 5 Cap\u00edtulo 14 22:31 Tesoro 1 22:44 Tesoros 2 y 3 23:18 Tesoro 4 23:28 Tesoro 5 23:41 Tesoro 6 23:57 Tesoro 7 24:13 Tesoro 8 24:32 Tesoro 9 Cap\u00edtulo 15 24:46 Tesoro 1 Cap\u00edtulo 16 25:00 Tesoro 1 25:13 Tesoro 2 25:26 Tesoro 3 Cap\u00edtulo 17 25:46 Tesoro 1 25:56 Tesoro 2 26:13 Tesoro 3 26:24 Tesoro 4 26:37 Tesoro 5 26:59 Tesoro 6 Cap\u00edtulo 18 27:18 Tesoro 1 27:34 Tesoro 2 27:59 Tesoro 3 28:16 Tesoro 4 28:26 Tesoro 5 28:41 Tesoro 6 28:55 Tesoro 7 29:07 Tesoro 8 Cap\u00edtulo 19 29:26 Tesoro 1 29:36 Tesoro 2 Cap\u00edtulo 20 29:50 Tesoro 1 30:06 Tesoro 2 30:20 Tesoro 3 30:34 Tesoros 4 y 5 Cap\u00edtulo 21 31:10 Tesoro 1 31:24 Tesoro 2 31:35 Tesoro 3 31:55 Tesoro 4 Cap\u00edtulo 22 32:11 Tesoro 1 Todas las gu\u00edas de Uncharted 4: El desenlace del ladr\u00f3n: https:\/\/www.youtube.com\/playlist?list=PLUEaSJ4rKZoJ7vUtjZ6xHz8WCFh2uCwT0 #Uncharted4 #Uncharted #Gu\u00edaDeTrofeos Suscr\u00edbete y activa la campana si quieres recibir un aviso cada vez que suba un v\u00eddeo: https:\/\/www.youtube.com\/subscription_center?add_user=GPAP360 ------ Redes sociales: Twitter: https:\/\/twitter.com\/_JavierParrado_ Facebook: https:\/\/www.facebook.com\/GuiasPasoAPaso360\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<h2>Trofeu &quot;Gamberro Tumulari&quot;<\/h2>\n<p>Per desbloquejar aquest trofeu de <strong>Uncharted 4<\/strong> hem de trobar els <strong>16 T\u00famuls de Roca al Cap\u00edtol 10<\/strong>. Podem destruir-los amb el cotxe o disparant-los amb una arma, quan ho fem amb els 16 desbloquejarem el trofeu. A continuaci\u00f3 us deixem un v\u00eddeo amb la localitzaci\u00f3 de tots els T\u00famuls de Roca.<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"Uncharted 4: Trofeu &quot;TUMULS DE ROCA&quot;\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_y7F2GW7w_7o\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/y7F2GW7w_7o\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/y7F2GW7w_7o\" \/><meta itemprop=\"duration\" content=\"PT5M15S\" \/><meta itemprop=\"uploadDate\" content=\"2016-05-11T08:51:16Z\" \/><\/div><div id=\"lyte_y7F2GW7w_7o\" data-src=\"https:\/\/i.ytimg.com\/vi\/y7F2GW7w_7o\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Uncharted 4: Trofeu &quot;TUMULS DE ROCA&quot;<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/y7F2GW7w_7o\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/y7F2GW7w_7o\/0.jpg\" alt=\"Uncharted 4: Trofeu &quot;TUMULS DE ROCA&quot;\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Deja tu like, comentario y suscr\u00edbete!! Tambi\u00e9n puedes seguirnos en las redes sociales: https:\/\/twitter.com\/geangoal https:\/\/www.instagram.com\/geangoal\/\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<h2>Trofeu &quot;Segueixo en Forma&quot;<\/h2>\n<p>Aquest trofeu ho aconseguim a les golfes del <strong>Cap\u00edtol 4<\/strong>, al vestidor que hi ha al fons a la dreta trobem una <strong>pistola de joguina<\/strong> i disparar a <strong>4 dianes<\/strong> que tenim penjant del sostre, aix\u00ed que les encertem saltar\u00e0 el trofeu. Us deixem un v\u00eddeo perqu\u00e8 no tingueu cap problema a obtenir-lo.&nbsp;<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"Uncharted 4: El desenlla\u00e7 del lladre | Trofeu: Segueixo en forma! (Cap\u00edtol 4)\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_ovbLlfldOSA\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/ovbLlfldOSA\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/ovbLlfldOSA\" \/><meta itemprop=\"duration\" content=\"PT59S\" \/><meta itemprop=\"uploadDate\" content=\"2016-05-10T13:36:02Z\" \/><\/div><div id=\"lyte_ovbLlfldOSA\" data-src=\"https:\/\/i.ytimg.com\/vi\/ovbLlfldOSA\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Uncharted 4: El desenlla\u00e7 del lladre | Trofeu: Segueixo en forma! (Cap\u00edtol 4)<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/ovbLlfldOSA\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/ovbLlfldOSA\/0.jpg\" alt=\"Uncharted 4: El desenlla\u00e7 del lladre | Trofeu: Segueixo en forma! (Cap\u00edtol 4)\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Hola muy buenas a todos, bienvenidos a este v\u00eddeo en el que ense\u00f1ar\u00e9 c\u00f3mo conseguir el Trofeo Sigo en forma en Uncharted 4: El desenlace del ladr\u00f3n. Para conseguir el trofeo hay que jugar en el cuarto cap\u00edtulo y disparar a las cuatro dianas que veremos en la guardilla usando la pistola de juguete. \u00a1Sigo en forma! Acierta a todos los objetivos en el \u00e1tico con la pistola de juguete. Still Got It! Hit all targets in the attic with the toy gun Todas las gu\u00edas de Uncharted 4: El desenlace del ladr\u00f3n: https:\/\/www.youtube.com\/playlist?list=PLUEaSJ4rKZoJ7vUtjZ6xHz8WCFh2uCwT0 #Uncharted4 #Uncharted #Gu\u00edaDeTrofeos Suscr\u00edbete y activa la campana si quieres recibir un aviso cada vez que suba un v\u00eddeo: https:\/\/www.youtube.com\/subscription_center?add_user=GPAP360 ------ Redes sociales: Twitter: https:\/\/twitter.com\/_JavierParrado_ Facebook: https:\/\/www.facebook.com\/GuiasPasoAPaso360\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<h2>Trofeu &quot;Fantasmes al Cementiri&quot;<\/h2>\n<p>Per aconseguir aquest trofeu hem de creuar el <strong>cementiri del Cap\u00edtol 8 \u2013 La tomba d&#039;Henry Avery<\/strong>, sense que ens detecti cap enemic ni matar-ne cap. Us deixem un v\u00eddeo per veure com s&#039;aconsegueix.<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"Uncharted 4: El desenlla\u00e7 del lladre | Trofeu: Fantasma al cementiri (Cap\u00edtol 8)\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_rReVGKGQcNw\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/rReVGKGQcNw\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/rReVGKGQcNw\" \/><meta itemprop=\"duration\" content=\"PT2M8S\" \/><meta itemprop=\"uploadDate\" content=\"2016-05-10T20:20:53Z\" \/><\/div><div id=\"lyte_rReVGKGQcNw\" data-src=\"https:\/\/i.ytimg.com\/vi\/rReVGKGQcNw\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Uncharted 4: El desenlla\u00e7 del lladre | Trofeu: Fantasma al cementiri (Cap\u00edtol 8)<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/rReVGKGQcNw\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/rReVGKGQcNw\/0.jpg\" alt=\"Uncharted 4: El desenlla\u00e7 del lladre | Trofeu: Fantasma al cementiri (Cap\u00edtol 8)\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Hola muy buenas a todos, bienvenidos a este v\u00eddeo en el que ense\u00f1ar\u00e9 c\u00f3mo conseguir el Trofeo Fantasma en el cementerio en Uncharted 4: El desenlace del ladr\u00f3n. Para conseguir el trofeo tendremos que cruzar el cementerio del cap\u00edtulo 8 sin que nos detecten los enemigos y sin acabar con ninguno de ellos. Fantasma en el cementerio Supera el encuentro de combate en el cementerio de Escocia sin matar ni ser visto. Ghost in the Cemetery Get through Scotland cemetery combat encounter without killing or being seen Todas las gu\u00edas de Uncharted 4: El desenlace del ladr\u00f3n: https:\/\/www.youtube.com\/playlist?list=PLUEaSJ4rKZoJ7vUtjZ6xHz8WCFh2uCwT0 #Uncharted4 #Uncharted #Gu\u00edaDeTrofeos Suscr\u00edbete y activa la campana si quieres recibir un aviso cada vez que suba un v\u00eddeo: https:\/\/www.youtube.com\/subscription_center?add_user=GPAP360 ------ Redes sociales: Twitter: https:\/\/twitter.com\/_JavierParrado_ Facebook: https:\/\/www.facebook.com\/GuiasPasoAPaso360\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<h2>Trofeu &quot;Salt de la de Rana&quot;<\/h2>\n<p>Per aconseguir aquest trofeu hem d&#039;acabar amb <strong>10 enemics<\/strong> alternant entre arma i cops de puny a la <strong>zona <\/strong>de les <strong>Ru\u00efnes<\/strong> del <strong>Cap\u00edtol 8 \u2013 La tomba d&#039;Henry Avery.&nbsp;<\/strong>Us deixem un v\u00eddeo perqu\u00e8 veieu com s&#039;aconsegueix f\u00e0cilment.<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"Uncharted 4: El desenlla\u00e7 del lladre | Trofeu: Salt de la granota (Cap\u00edtol 8)\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_CNOISFw8Yx8\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/CNOISFw8Yx8\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/CNOISFw8Yx8\" \/><meta itemprop=\"duration\" content=\"PT1M47S\" \/><meta itemprop=\"uploadDate\" content=\"2016-05-09T18:42:40Z\" \/><\/div><div id=\"lyte_CNOISFw8Yx8\" data-src=\"https:\/\/i.ytimg.com\/vi\/CNOISFw8Yx8\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Uncharted 4: El desenlla\u00e7 del lladre | Trofeu: Salt de la granota (Cap\u00edtol 8)<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/CNOISFw8Yx8\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/CNOISFw8Yx8\/0.jpg\" alt=\"Uncharted 4: El desenlla\u00e7 del lladre | Trofeu: Salt de la granota (Cap\u00edtol 8)\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Hola muy buenas a todos, bienvenidos a este v\u00eddeo en el que ense\u00f1ar\u00e9 c\u00f3mo conseguir el Trofeo Salto de la rana en Uncharted 4: El desenlace del ladr\u00f3n. Para conseguir el trofeo hay que acabar con 10 enemigos seguidos alternando entre el arma y los pu\u00f1os. Primero usaremos el arma para acabar con cualquier enemigo y con el siguiente los pu\u00f1os. Tenemos que repetir este proceso cinco veces para conseguir el trofeo. Salto de la rana Elimina a 10 enemigos seguidos alternando disparos y combate cuerpo a cuerpo. Leapfrog Defeat 10 enemies in a row, alternating gunplay and hand-to-hand Todas las gu\u00edas de Uncharted 4: El desenlace del ladr\u00f3n: https:\/\/www.youtube.com\/playlist?list=PLUEaSJ4rKZoJ7vUtjZ6xHz8WCFh2uCwT0 #Uncharted4 #Uncharted #Gu\u00edaDeTrofeos Suscr\u00edbete y activa la campana si quieres recibir un aviso cada vez que suba un v\u00eddeo: https:\/\/www.youtube.com\/subscription_center?add_user=GPAP360 ------ Redes sociales: Twitter: https:\/\/twitter.com\/_JavierParrado_ Facebook: https:\/\/www.facebook.com\/GuiasPasoAPaso360\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<p>Guia completa per Uncharted 4 punxant <a href=\"http:\/\/www.vandal.net\/guias\/guia-uncharted-4-el-desenlace-del-ladron\" title=\"Guia completa Uncharted 4\">aqu\u00ed<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Descobreix tots els secrets de l&#039;\u00faltim joc de la saga Naughty Dog<\/p>","protected":false},"author":2,"featured_media":349,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[70],"class_list":["post-348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videojuegos","tag-ocio"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trucos Uncharted 4 para PS4 - Trucos.com<\/title>\n<meta name=\"description\" content=\"Descubre todos los secretos del \u00faltimo juego de la exitosa saga Naughty Dog\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trucos.com\/ca\/videojocs\/trucs-uncharted-4-per-a-ps4\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trucos Uncharted 4 para PS4 - Trucos.com\" \/>\n<meta property=\"og:description\" content=\"Descubre todos los secretos del \u00faltimo juego de la exitosa saga Naughty Dog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trucos.com\/ca\/videojocs\/trucs-uncharted-4-per-a-ps4\/\" \/>\n<meta property=\"og:site_name\" content=\"Trucos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trucoscom\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-26T16:19:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Uncharted_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trucs Uncharted 4 per PS4 - Trucos.com","description":"Descobreix tots els secrets de l&#039;\u00faltim joc de la saga Naughty Dog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trucos.com\/ca\/videojocs\/trucs-uncharted-4-per-a-ps4\/","og_locale":"ca_ES","og_type":"article","og_title":"Trucos Uncharted 4 para PS4 - Trucos.com","og_description":"Descubre todos los secretos del \u00faltimo juego de la exitosa saga Naughty Dog","og_url":"https:\/\/trucos.com\/ca\/videojocs\/trucs-uncharted-4-per-a-ps4\/","og_site_name":"Trucos.com","article_publisher":"https:\/\/www.facebook.com\/trucoscom\/","article_published_time":"2016-05-26T16:19:17+00:00","og_image":[{"width":620,"height":330,"url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Uncharted_4.jpg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Redaccion","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/#article","isPartOf":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/"},"author":{"name":"Redaccion","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536"},"headline":"Trucos Uncharted 4 para PS4","datePublished":"2016-05-26T16:19:17+00:00","mainEntityOfPage":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/"},"wordCount":544,"publisher":{"@id":"https:\/\/trucos.com\/#organization"},"image":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Uncharted_4.jpg","keywords":["Ocio"],"articleSection":["Videojuegos"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/","url":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/","name":"Trucs Uncharted 4 per PS4 - Trucos.com","isPartOf":{"@id":"https:\/\/trucos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/#primaryimage"},"image":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Uncharted_4.jpg","datePublished":"2016-05-26T16:19:17+00:00","description":"Descobreix tots els secrets de l&#039;\u00faltim joc de la saga Naughty Dog","breadcrumb":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/#primaryimage","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Uncharted_4.jpg","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Uncharted_4.jpg","width":620,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/trucos.com\/videojuegos\/trucos-uncharted-4-para-ps4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trucos.com\/"},{"@type":"ListItem","position":2,"name":"Trucos Uncharted 4 para PS4"}]},{"@type":"WebSite","@id":"https:\/\/trucos.com\/#website","url":"https:\/\/trucos.com\/","name":"Trucos.com","description":"Els millors trucs sobre videojocs, tecnologia i m\u00f2bils","publisher":{"@id":"https:\/\/trucos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trucos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/trucos.com\/#organization","name":"Trucos.com","url":"https:\/\/trucos.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","width":207,"height":68,"caption":"Trucos.com"},"image":{"@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trucoscom\/"]},{"@type":"Person","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","caption":"Redaccion"},"sameAs":["http:\/\/trucos.com"],"url":"https:\/\/trucos.com\/ca\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/posts\/348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/comments?post=348"}],"version-history":[{"count":0,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/posts\/348\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/media\/349"}],"wp:attachment":[{"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/media?parent=348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/categories?post=348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trucos.com\/ca\/wp-json\/wp\/v2\/tags?post=348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}