{"id":1370,"date":"2019-02-03T19:34:17","date_gmt":"2019-02-03T19:34:17","guid":{"rendered":"http:\/\/trucos.com\/uncategorized\/whatsapp-como-grabar-un-video-y-crear-un-gif-para-enviarlo\/"},"modified":"2019-02-03T19:34:17","modified_gmt":"2019-02-03T19:34:17","slug":"whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer","status":"publish","type":"post","link":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/","title":{"rendered":"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer"},"content":{"rendered":"<p>Voulez-vous cr\u00e9er le v\u00f4tre <strong>GIF<\/strong> avec <a href=\"https:\/\/www.whatsapp.com\/\"><strong>WhatsApp<\/strong><\/a> les partager avec vos contacts ? Gr\u00e2ce \u00e0 ce tutoriel, vous pourrez cr\u00e9er vos propres clips anim\u00e9s au lieu de <a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-creer-une-recherche-et-envoyer-des-animations-gif-sur-whatsapp\/\">rechercher des GIF d\u00e9j\u00e0 cr\u00e9\u00e9s<\/a> via le moteur de recherche de l&#039;application ou utilisez un cr\u00e9ateur externe tel que <a href=\"https:\/\/giphy.com\/\"><strong>Giphy<\/strong><\/a>; et d\u00e9sormais, il sera plus facile que jamais d&#039;enregistrer une vid\u00e9o via <a href=\"http:\/\/trucos.com\/fr\/mobiles\/astuces-whatsapp-comment-savoir-sils-mont-bloque\/\"><strong>WhatsApp<\/strong><\/a> et convertissez-en quelques secondes en fichier GIF, tout cela gr\u00e2ce au <strong>Syst\u00e8me de cr\u00e9ation de GIF WhatsApp<\/strong>, tous deux issus du <a href=\"http:\/\/www.amazon.es\/Samsung-Galaxy-Plus-Smartphone-Bluetooth\/dp\/B079XF3BYL\/ref=sr_1_1?ie=UTF8&amp;qid=1521044485&amp;sr=8-1&amp;keywords=galaxy+s9&amp;tag=cmvr0d-21\">cam\u00e9ra mobile<\/a> \u00e0 partir de la galerie vid\u00e9o du terminal. Ensuite, <strong>comment cr\u00e9er un GIF avec <a href=\"http:\/\/trucos.com\/fr\/mobiles\/whatsapp-explique-comment-voir-les-statuts-des-utilisateurs-sans-quils-le-sachent\/\">WhatsApp<\/a> pour les envoyer \u00e0 nos contacts<\/strong>.<\/p>\n<div class=\"lyte-wrapper fourthree\" title=\"Comment cr\u00e9er et envoyer des GIF sur WhatsApp TRICKS Partie 11 - Comment configurer\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_SdvlPNOCCn0\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/SdvlPNOCCn0\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/SdvlPNOCCn0\" \/><meta itemprop=\"duration\" content=\"PT2M44S\" \/><meta itemprop=\"uploadDate\" content=\"2017-10-25T09:00:02Z\" \/><\/div><div id=\"lyte_SdvlPNOCCn0\" data-src=\"https:\/\/i.ytimg.com\/vi\/SdvlPNOCCn0\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Comment cr\u00e9er et envoyer des GIF sur WhatsApp TRICKS Partie 11 - Comment configurer<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/SdvlPNOCCn0\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/SdvlPNOCCn0\/0.jpg\" alt=\"Comment cr\u00e9er et envoyer des GIF sur WhatsApp TRICKS Partie 11 - Comment configurer\" width=\"420\" height=\"295\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Mira C\u00f3mo hacer un GIF animado por WhatsApp muy Facil. TOP 10 Trucos de WhatsApp Aqui : https:\/\/www.youtube.com\/playlist?list=PLHlbmuv4l8hLz_d73PQkz4zOKlUQVyfG3 \u25ba\u25ba Donde Comprar Tel\u00e9fonos Potentes : https:\/\/goo.gl\/juBiY3 \u25ba Donde Comprar Drones : https:\/\/goo.gl\/aoGi9t Suscr\u00edbete al Canal: https:\/\/goo.gl\/EILJiW S\u00edgueme en mis Redes sociales: https:\/\/www.facebook.com\/ComoConfigurarPage https:\/\/twitter.com\/Comoconfigurar https:\/\/instagram.com\/comoconfigurar\/\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/p>\n<h2>Comment cr\u00e9er un GIF avec la cam\u00e9ra WhatsApp<\/h2>\n<p>La premi\u00e8re \u00e9tape est <strong>ouvrir <a href=\"http:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-synchroniser-vos-photos-avec-google-photos-icloud-et-onedrive\/\">WhatsApp<\/a><\/strong> et <strong>d\u00e9marrer une conversation avec la personne<\/strong> auquel vous souhaitez envoyer votre propre GIF. Maintenant <strong>acc\u00e9der \u00e0 la cam\u00e9ra via l&#039;ic\u00f4ne<\/strong> de la conversation elle-m\u00eame situ\u00e9e dans le bar <strong>\u00c9crire un message<\/strong> du bas de l\u2019\u00e9cran. La premi\u00e8re fois que vous acc\u00e9dez \u00e0 la cam\u00e9ra via cette ic\u00f4ne, l&#039;application vous demandera si vous autorisez WhatsApp \u00e0 acc\u00e9der \u00e0 la cam\u00e9ra ; cliquer sur <strong>Permettre<\/strong>.<\/p>\n<p><img decoding=\"async\" alt=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" src=\"\/media\/upload\/2019\/02\/03\/whatsapp-gif-01.jpg\" style=\"width:100%\" title=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" \/><\/p>\n<p>D\u00e9j\u00e0 \u00e0 l&#039;int\u00e9rieur de la cam\u00e9ra WhatsApp, <strong>appuyez et maintenez le bouton rouge d&#039;enregistrement vid\u00e9o<\/strong> au lieu de prendre une photo ; Tant que vous appuyez sur le bouton rouge, la vid\u00e9o sera enregistr\u00e9e. Ne vous inqui\u00e9tez pas de la dur\u00e9e de la vid\u00e9o\u00a0; Ensuite vous pourrez couper la s\u00e9quence qui vous int\u00e9resse. <strong>Enregistrez quelques secondes de vid\u00e9o<\/strong>.<\/p>\n<p><img decoding=\"async\" alt=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" src=\"\/media\/upload\/2019\/02\/03\/whatsapp-gif-02.jpg\" style=\"width:100%\" title=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" \/><\/p>\n<p>Quand vous souhaitez arr\u00eater l&#039;enregistrement <strong>rel\u00e2chez le bouton<\/strong> et l&#039;enregistrement vid\u00e9o s&#039;arr\u00eatera instantan\u00e9ment, passant au <strong>\u00e9cran de montage vid\u00e9o<\/strong> automatiquement. Maintenant vous pouvez <strong>recadrer la vid\u00e9o sur les deux marges<\/strong>&nbsp;de sa timeline situ\u00e9e en haut de l&#039;\u00e9cran ; Le fragment \u00e0 l\u2019int\u00e9rieur sera la s\u00e9quence GIF r\u00e9sultante. Coupez la vid\u00e9o pour la faire durer <strong>moins de six secondes<\/strong>. Au fur et \u00e0 mesure que vous d\u00e9placez les marges, la dur\u00e9e et le poids du GIF que vous cr\u00e9ez appara\u00eetront \u00e0 l&#039;\u00e9cran.<\/p>\n<p><img decoding=\"async\" alt=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" src=\"\/media\/upload\/2019\/02\/03\/whatsapp-gif-03.jpg\" style=\"width:100%\" title=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" \/><\/p>\n<p>Lorsque vous avez s\u00e9lectionn\u00e9 la s\u00e9quence vid\u00e9o pour votre GIF (toujours moins de six secondes) <strong>un bouton appara\u00eetra sous la barre<\/strong> chronologie, sur le c\u00f4t\u00e9 droit. <strong>S\u00e9lectionnez l&#039;option GIF<\/strong> pour que WhatsApp convertisse automatiquement la vid\u00e9o ; Une fois pr\u00eat, vous pouvez ajouter du texte ou des autocollants au GIF comme s&#039;il s&#039;agissait d&#039;une vid\u00e9o.<\/p>\n<p><img decoding=\"async\" alt=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" src=\"\/media\/upload\/2019\/02\/03\/whatsapp-gif-04.jpg\" style=\"width:100%\" title=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" \/><\/p>\n<p>Lorsque vous envoyez la vid\u00e9o d\u00e9j\u00e0 \u00e9dit\u00e9e avec l&#039;option GIF, vous enverrez le fichier GIF \u00e0 la place de la vid\u00e9o. <strong>Votre contact recevra le GIF<\/strong> directement sans avoir \u00e0 recourir \u00e0 des \u00e9diteurs externes ou \u00e0 des sites Web comme Giphy.<\/p>\n<p><img decoding=\"async\" alt=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" src=\"\/media\/upload\/2019\/02\/03\/whatsapp-gif-05.jpg\" style=\"width:100%\" title=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" \/><\/p>\n<h2>Comment cr\u00e9er des GIF \u00e0 partir des vid\u00e9os de votre galerie<\/h2>\n<p>En plus de cr\u00e9er des vid\u00e9os directement depuis la cam\u00e9ra WhatsApp, nous pouvons \u00e9galement <strong>cr\u00e9er des GIF \u00e0 partir des vid\u00e9os que nous avons stock\u00e9es<\/strong> dans la galerie vid\u00e9o de notre mobile. Pour ce faire, cliquez sur l&#039;ic\u00f4ne du clip situ\u00e9e dans la barre d&#039;outils. <strong>\u00c9crire un message<\/strong> joindre le fichier puis cliquez sur l&#039;ic\u00f4ne <strong>Galerie<\/strong> pour acc\u00e9der au contenu multim\u00e9dia stock\u00e9 sur notre mobile.<\/p>\n<p><img decoding=\"async\" alt=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" src=\"\/media\/upload\/2019\/02\/03\/whatsapp-gif-06.jpg\" style=\"width:100%\" title=\"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer\" \/><\/p>\n<p>Maintenant <strong>choisissez une vid\u00e9o \u00e0 partir de laquelle vous souhaitez cr\u00e9er un GIF<\/strong>; Lorsque nous s\u00e9lectionnons la vid\u00e9o, nous pouvons la modifier, la d\u00e9couper et cr\u00e9er le GIF\u00a0; Et lorsque nous s\u00e9lectionnerons la vid\u00e9o, nous acc\u00e9derons directement au menu d\u2019\u00e9dition comme si nous venions de l\u2019enregistrer. <strong>Suivez les m\u00eames \u00e9tapes que le tutoriel pr\u00e9c\u00e9dent<\/strong> pour cr\u00e9er le GIF et l&#039;envoyer \u00e0 vos contacts.<\/p>\n<h2>Plus d&#039;astuces sur WhatsApp :<\/h2>\n<ul>\n<li><a href=\"http:\/\/trucos.com\/fr\/mobiles\/whatsapp-explique-comment-voir-les-statuts-des-utilisateurs-sans-quils-le-sachent\/\">Astuces WhatsApp\u00a0: Comment voir les statuts des utilisateurs \u00e0 leur insu<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-synchroniser-vos-photos-avec-google-photos-icloud-et-onedrive\/\">WhatsApp : Comment synchroniser vos photos avec le cloud<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-installer-des-autocollants-de-telegramme-sur-votre-mobile\/\">WhatsApp : Comment installer des autocollants Telegram sur votre mobile<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/mobiles\/astuces-whatsapp-comment-savoir-sils-mont-bloque\/\">Astuces WhatsApp : Comment savoir s&#039;ils m&#039;ont bloqu\u00e9<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Apprenez \u00e0 enregistrer une vid\u00e9o et \u00e0 cr\u00e9er un GIF directement dans WhatsApp<\/p>","protected":false},"author":2,"featured_media":1371,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[19],"class_list":["post-1370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moviles","tag-tecnologia"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WhatsApp: C\u00f3mo grabar un v\u00eddeo y crear un GIF para enviarlo - Trucos.com<\/title>\n<meta name=\"description\" content=\"Aprende a grabar un v\u00eddeo y crear un GIF directamente en WhatsApp\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WhatsApp: C\u00f3mo grabar un v\u00eddeo y crear un GIF para enviarlo - Trucos.com\" \/>\n<meta property=\"og:description\" content=\"Aprende a grabar un v\u00eddeo y crear un GIF directamente en WhatsApp\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/\" \/>\n<meta property=\"og:site_name\" content=\"Trucos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trucoscom\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-03T19:34:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-gif.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer - Trucos.com","description":"Apprenez \u00e0 enregistrer une vid\u00e9o et \u00e0 cr\u00e9er un GIF directement dans WhatsApp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/","og_locale":"fr_FR","og_type":"article","og_title":"WhatsApp: C\u00f3mo grabar un v\u00eddeo y crear un GIF para enviarlo - Trucos.com","og_description":"Aprende a grabar un v\u00eddeo y crear un GIF directamente en WhatsApp","og_url":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/","og_site_name":"Trucos.com","article_publisher":"https:\/\/www.facebook.com\/trucoscom\/","article_published_time":"2019-02-03T19:34:17+00:00","og_image":[{"width":700,"height":450,"url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-gif.jpg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redaccion","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/#article","isPartOf":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/"},"author":{"name":"Redaccion","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536"},"headline":"WhatsApp: C\u00f3mo grabar un v\u00eddeo y crear un GIF para enviarlo","datePublished":"2019-02-03T19:34:17+00:00","mainEntityOfPage":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/"},"wordCount":821,"publisher":{"@id":"https:\/\/trucos.com\/#organization"},"image":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-gif.jpg","keywords":["Tecnologia"],"articleSection":["M\u00f3viles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/","url":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/","name":"WhatsApp : Comment enregistrer une vid\u00e9o et cr\u00e9er un GIF pour l&#039;envoyer - Trucos.com","isPartOf":{"@id":"https:\/\/trucos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/#primaryimage"},"image":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-gif.jpg","datePublished":"2019-02-03T19:34:17+00:00","description":"Apprenez \u00e0 enregistrer une vid\u00e9o et \u00e0 cr\u00e9er un GIF directement dans WhatsApp","breadcrumb":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/#primaryimage","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-gif.jpg","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-gif.jpg","width":700,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/trucos.com\/fr\/mobiles\/whatsapp-comment-enregistrer-une-video-et-creer-un-gif-pour-lenvoyer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trucos.com\/"},{"@type":"ListItem","position":2,"name":"WhatsApp: C\u00f3mo grabar un v\u00eddeo y crear un GIF para enviarlo"}]},{"@type":"WebSite","@id":"https:\/\/trucos.com\/#website","url":"https:\/\/trucos.com\/","name":"Astuces.com","description":"Les meilleures astuces sur les jeux vid\u00e9o, la technologie et les t\u00e9l\u00e9phones portables","publisher":{"@id":"https:\/\/trucos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trucos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trucos.com\/#organization","name":"Astuces.com","url":"https:\/\/trucos.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","width":207,"height":68,"caption":"Trucos.com"},"image":{"@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trucoscom\/"]},{"@type":"Person","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536","name":"Redaction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","caption":"Redaccion"},"sameAs":["http:\/\/trucos.com"],"url":"https:\/\/trucos.com\/fr\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/1370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/comments?post=1370"}],"version-history":[{"count":0,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/1370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media\/1371"}],"wp:attachment":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media?parent=1370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/categories?post=1370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/tags?post=1370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}