{"id":2105,"date":"2020-07-17T17:40:27","date_gmt":"2020-07-17T17:40:27","guid":{"rendered":"http:\/\/trucos.com\/uncategorized\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/"},"modified":"2020-07-17T17:40:27","modified_gmt":"2020-07-17T17:40:27","slug":"comment-passer-des-appels-video-avec-whatsapp-de-plus-de-4","status":"publish","type":"post","link":"https:\/\/trucos.com\/fr\/mobiles\/comment-passer-des-appels-video-avec-whatsapp-de-plus-de-4\/","title":{"rendered":"Comment passer des appels vid\u00e9o avec WhatsApp de plus de 4"},"content":{"rendered":"<p>Ci-dessous, nous vous apprenons <strong>comment faire <a href=\"http:\/\/trucos.com\/fr\/linternet\/comment-passer-des-appels-video-gratuits-et-des-discussions-video-de-groupe\/\">appels vid\u00e9o<\/a> sur WhatsApp de plus de 4 personnes<\/strong>, une fonctionnalit\u00e9 qui a \u00e9t\u00e9 impl\u00e9ment\u00e9e gr\u00e2ce \u00e0 de nouvelles mises \u00e0 jour et permet \u00e0 ses utilisateurs de participer \u00e0 <strong>chats vid\u00e9o avec plus de quatre participants<\/strong>. Ainsi, il est d\u00e9sormais possible aux familles et groupes d&#039;amis de participer \u00e0 <a href=\"http:\/\/trucos.com\/fr\/linternet\/comment-passer-un-appel-sur-skype\/\">r\u00e9unions virtuelles<\/a> via la populaire application de messagerie avec une limite de huit personnes maximum. Bien entendu, pour profiter de cette nouvelle mise \u00e0 jour, il faudra avoir le <strong>derni\u00e8re version disponible de <a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-creer-un-compte-whatsapp-messenger-gratuit\/\">WhatsApp<\/a><\/strong>, tous deux sur mobile <a href=\"https:\/\/apps.apple.com\/es\/app\/whatsapp-messenger\/id310633997\">IOS<\/a> comme dans <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.whatsapp&amp;hl=es\">Android<\/a>. Ne manquez pas notre tutoriel sur <strong>comment passer des appels vid\u00e9o avec <a href=\"https:\/\/www.whatsapp.com\/?lang=es\">WhatsApp<\/a> de plus de 4 personnes<\/strong>.<\/p>\n<div class=\"lyte-wrapper fourthree\" title=\"WHATSAPP : appels vid\u00e9o avec JUSQU&#039;\u00c0 8 PERSONNES ! | FilleGeek\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_fN370xDfyZE\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/fN370xDfyZE\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/fN370xDfyZE\" \/><meta itemprop=\"duration\" content=\"PT5M36S\" \/><meta itemprop=\"uploadDate\" content=\"2020-04-29T12:45:31Z\" \/><\/div><div id=\"lyte_fN370xDfyZE\" data-src=\"https:\/\/i.ytimg.com\/vi\/fN370xDfyZE\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">WHATSAPP : appels vid\u00e9o avec JUSQU&#039;\u00c0 8 PERSONNES ! | FilleGeek<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/fN370xDfyZE\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/fN370xDfyZE\/0.jpg\" alt=\"WHATSAPP : appels vid\u00e9o avec JUSQU&#039;\u00c0 8 PERSONNES ! | FilleGeek\" width=\"420\" height=\"295\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"\u2022 Seguro que ya sabes que en WhatsApp se pueden hacer videollamadas con hasta 4 participantes... \u00a1Pues NO! Eso era hasta ahora, porque con la \u00faltima versi\u00f3n de la app se ha aumentado el l\u00edmite. Ahora puedes hacer videollamadas en WhatsApp de un m\u00e1ximo de 8 personas! \u2022 Para hacer estas videollamadas grupales de Whatsapp, es importante que tengas actualizada la aplicaci\u00f3n a su versi\u00f3n m\u00e1s reciente. Es imprescindible tambi\u00e9n que todos los participantes en la videollamada de grupo est\u00e9n tambi\u00e9n actualizados. \u2022 Teniendo esos requisitos en cuenta, hacer una videollamada grupal en WhatsApp con hasta 8 personas es muy f\u00e1cil, ya que se hace igual que siempre: puedes iniciar la llamada grupal directamente desde la pesta\u00f1a de Llamadas dentro de la app, o ir a\u00f1adiendo gente una por una a una videollamada ya activa. En el v\u00eddeo te muestro ambos m\u00e9todos. \u2022 \u00a1A partir de ahora tus videollamadas grupales de WhatsApp pueden convertirse en toda una fiesta! \u2b50\ufe0f GRACIAS a mis compa\u00f1eras de videollamada \u2b50\ufe0f - https:\/\/www.instagram.com\/elviajedelosmartes - https:\/\/www.instagram.com\/lavidawhatelse #whatsapp #videollamadas #grupales \u25b7 Mi tienda de camisetas http:\/\/bit.ly\/camisetas-chicageek \u2764\ufe0f \u25b7 Mi equipo de grabaci\u00f3n: https:\/\/kit.co\/chicageek \ud83d\udcf8 \u25b7 \u00a1S\u00edgueme en redes sociales para saber m\u00e1s de m\u00ed! \u26a1\ufe0f INSTAGRAM https:\/\/www.instagram.com\/chicageek \u26a1\ufe0f TWITTER https:\/\/twitter.com\/chicageek \u25b7 Suscr\u00edbete a mi canal para no perderte nada. \u00a1V\u00eddeos nuevos cada semana! \ud83d\ude0a https:\/\/www.youtube.com\/chicageek?sub_confirmation=1 \u25b7 Hago an\u00e1lisis de gadgets, te descubro las apps de m\u00f3vil m\u00e1s interesantes y te ense\u00f1o los mejores trucos, consejos y tutoriales para sacarle todo el partido a la tecnolog\u00eda \ud83d\udcf1 \ud83d\udcbb \ud83d\udd79\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/p>\n<h2>Appels vid\u00e9o WhatsApp de plus de 4\u00a0: comment ils fonctionnent<\/h2>\n<p>Ainsi, les appels vid\u00e9o avec plus de 4 utilisateurs sont d\u00e9sormais disponibles sur WhatsApp, nous pouvons donc d\u00e9sormais participer <strong>r\u00e9unions virtuelles audio et vid\u00e9o<\/strong> avec plus de participants que jamais. Bien entendu, il existe une limite d\u2019utilisateurs dans ce type de chat vid\u00e9o\u00a0; \u00e0 tel point que la limite du nombre de personnes pouvant participer \u00e0 un <a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-ne-pas-apparaitre-en-ligne-sur-whatsapp\/\">appel vid\u00e9o de groupe<\/a> C&#039;est <strong>8 utilisateurs \u00e0 la fois<\/strong>. Cependant, la personne charg\u00e9e de passer l&#039;appel vid\u00e9o peut inviter jusqu&#039;\u00e0 sept personnes maximum dans la m\u00eame vid\u00e9oconf\u00e9rence.<\/p>\n<p><img decoding=\"async\" alt=\"Comment passer des appels vid\u00e9o avec WhatsApp de plus de 4\" src=\"\/media\/upload\/2020\/07\/17\/whatsapp-videollamadas-4-01.jpg\" style=\"width:100%\" title=\"Comment passer des appels vid\u00e9o avec WhatsApp de plus de 4\" \/><\/p>\n<h2>Comment passer un appel vid\u00e9o avec jusqu&#039;\u00e0 8 personnes<\/h2>\n<p>La premi\u00e8re \u00e9tape pour passer des appels vid\u00e9o avec plus de 4 utilisateurs et jusqu&#039;\u00e0 un maximum de 8 est de s&#039;assurer que tous les participants \u00e0 la vid\u00e9oconf\u00e9rence ont <strong>l&#039;application WhatsApp mise \u00e0 jour<\/strong> \u00e0 la derni\u00e8re version. De plus, tous les utilisateurs doivent <strong>faire partie du m\u00eame groupe WhatsApp<\/strong>. Une fois que nous avons rempli ces caract\u00e9ristiques, nous pouvons passer \u00e0 un appel vid\u00e9o avec plus de 4 personnes. Suivez les \u00e9tapes suivantes\u00a0:<\/p>\n<ol>\n<li>Ouvrez l&#039;application WhatsApp et acc\u00e9dez au groupe dans lequel vous souhaitez passer l&#039;appel vid\u00e9o avec plus de 4 utilisateurs ; N&#039;oubliez pas que le groupe doit contenir les utilisateurs auxquels vous souhaitez participer \u00e0 la vid\u00e9oconf\u00e9rence.<\/li>\n<li>Cliquez sur l&#039;ic\u00f4ne d&#039;appel repr\u00e9sent\u00e9e par une ic\u00f4ne de t\u00e9l\u00e9phone et un signe \u00ab+\u00bb situ\u00e9 dans le coin sup\u00e9rieur droit.<\/li>\n<li>S\u00e9lectionnez les contacts du groupe avec lesquels vous souhaitez passer l&#039;appel vid\u00e9o, jusqu&#039;\u00e0 un total de 7.<\/li>\n<li>Cliquez sur l&#039;ic\u00f4ne de la cam\u00e9ra vid\u00e9o qui appara\u00eet \u00e0 droite des contacts s\u00e9lectionn\u00e9s pour d\u00e9marrer l&#039;appel vid\u00e9o.<\/li>\n<li>Le reste des contacts s\u00e9lectionn\u00e9s du m\u00eame groupe recevront leurs notifications respectives sur leurs appareils mobiles et pourront accepter ou rejeter l&#039;appel vid\u00e9o.<\/li>\n<li>S&#039;ils acceptent, l&#039;appel vid\u00e9o commencera et vous pourrez leur parler par vid\u00e9oconf\u00e9rence.<\/li>\n<\/ol>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=YWhxnhW8OoU\"><img decoding=\"async\" alt=\"Comment passer des appels vid\u00e9o avec WhatsApp de plus de 4\" src=\"\/media\/upload\/2020\/07\/17\/yt.jpg\" style=\"width:100%\" title=\"Comment passer des appels vid\u00e9o avec WhatsApp de plus de 4\" \/><\/a><\/p>\n<h2>Plus d&#039;astuces sur WhatsApp<\/h2>\n<ul>\n<li><a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-supprimer-les-messages-whatsapp\/\">Comment supprimer les messages WhatsApp<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-creer-un-compte-whatsapp-messenger-gratuit\/\">Comment cr\u00e9er un compte WhatsApp Messenger gratuit<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-utiliser-les-memojis-sur-whatsapp\/\">Comment utiliser les m\u00e9mojis sur WhatsApp<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-ne-pas-apparaitre-en-ligne-sur-whatsapp\/\">Comment ne pas appara\u00eetre en ligne sur WhatsApp<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Tutoriel sur la fa\u00e7on de cr\u00e9er des chats vid\u00e9o sur WhatsApp avec plus de 4 utilisateurs<\/p>","protected":false},"author":2,"featured_media":2106,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[19],"class_list":["post-2105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moviles","tag-tecnologia"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo hacer videollamadas con WhatsApp de m\u00e1s de 4 - Trucos.com<\/title>\n<meta name=\"description\" content=\"Tutorial sobre c\u00f3mo hacer videochats en WhatsApp con m\u00e1s de 4 usuarios\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trucos.com\/fr\/mobiles\/comment-passer-des-appels-video-avec-whatsapp-de-plus-de-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo hacer videollamadas con WhatsApp de m\u00e1s de 4 - Trucos.com\" \/>\n<meta property=\"og:description\" content=\"Tutorial sobre c\u00f3mo hacer videochats en WhatsApp con m\u00e1s de 4 usuarios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trucos.com\/fr\/mobiles\/comment-passer-des-appels-video-avec-whatsapp-de-plus-de-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Trucos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trucoscom\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-17T17:40:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-videollamadas-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment passer des appels vid\u00e9o avec WhatsApp de plus de 4 - Trucos.com","description":"Tutoriel sur la fa\u00e7on de cr\u00e9er des chats vid\u00e9o sur WhatsApp avec plus de 4 utilisateurs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trucos.com\/fr\/mobiles\/comment-passer-des-appels-video-avec-whatsapp-de-plus-de-4\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00f3mo hacer videollamadas con WhatsApp de m\u00e1s de 4 - Trucos.com","og_description":"Tutorial sobre c\u00f3mo hacer videochats en WhatsApp con m\u00e1s de 4 usuarios","og_url":"https:\/\/trucos.com\/fr\/mobiles\/comment-passer-des-appels-video-avec-whatsapp-de-plus-de-4\/","og_site_name":"Trucos.com","article_publisher":"https:\/\/www.facebook.com\/trucoscom\/","article_published_time":"2020-07-17T17:40:27+00:00","og_image":[{"width":800,"height":599,"url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-videollamadas-4.jpg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redaccion","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/#article","isPartOf":{"@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/"},"author":{"name":"Redaccion","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536"},"headline":"C\u00f3mo hacer videollamadas con WhatsApp de m\u00e1s de 4","datePublished":"2020-07-17T17:40:27+00:00","mainEntityOfPage":{"@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/"},"wordCount":556,"publisher":{"@id":"https:\/\/trucos.com\/#organization"},"image":{"@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-videollamadas-4.jpg","keywords":["Tecnologia"],"articleSection":["M\u00f3viles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/","url":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/","name":"Comment passer des appels vid\u00e9o avec WhatsApp de plus de 4 - Trucos.com","isPartOf":{"@id":"https:\/\/trucos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/#primaryimage"},"image":{"@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-videollamadas-4.jpg","datePublished":"2020-07-17T17:40:27+00:00","description":"Tutoriel sur la fa\u00e7on de cr\u00e9er des chats vid\u00e9o sur WhatsApp avec plus de 4 utilisateurs","breadcrumb":{"@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/#primaryimage","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-videollamadas-4.jpg","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/whatsapp-videollamadas-4.jpg","width":800,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/trucos.com\/moviles\/como-hacer-videollamadas-con-whatsapp-de-mas-de-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trucos.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo hacer videollamadas con WhatsApp de m\u00e1s de 4"}]},{"@type":"WebSite","@id":"https:\/\/trucos.com\/#website","url":"https:\/\/trucos.com\/","name":"Astuces.com","description":"Les meilleures astuces sur les jeux vid\u00e9o, la technologie et les t\u00e9l\u00e9phones portables","publisher":{"@id":"https:\/\/trucos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trucos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trucos.com\/#organization","name":"Astuces.com","url":"https:\/\/trucos.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","width":207,"height":68,"caption":"Trucos.com"},"image":{"@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trucoscom\/"]},{"@type":"Person","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536","name":"Redaction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","caption":"Redaccion"},"sameAs":["http:\/\/trucos.com"],"url":"https:\/\/trucos.com\/fr\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/2105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/comments?post=2105"}],"version-history":[{"count":0,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/2105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media\/2106"}],"wp:attachment":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media?parent=2105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/categories?post=2105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/tags?post=2105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}