{"id":2701,"date":"2021-10-18T18:43:58","date_gmt":"2021-10-18T18:43:58","guid":{"rendered":"http:\/\/trucos.com\/uncategorized\/como-quitar-el-buzon-de-voz-de-yoigo\/"},"modified":"2023-08-03T13:59:29","modified_gmt":"2023-08-03T13:59:29","slug":"xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu","status":"publish","type":"post","link":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/","title":{"rendered":"Comment supprimer la messagerie vocale Yoigo"},"content":{"rendered":"<p>Voyons <strong>comment supprimer la messagerie vocale Yoigo<\/strong>, le r\u00e9pondeur du c\u00e9l\u00e8bre op\u00e9rateur de t\u00e9l\u00e9phonie mobile. Et quand tu engages une ligne <a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-nettoyer-le-haut-parleur-mobile\/\" target=\"_blank\" rel=\"noopener\">mobile<\/a> de Yoigo, le <strong>service de r\u00e9ponse<\/strong> afin que l&#039;utilisateur puisse enregistrer le num\u00e9ro <a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-savoir-si-votre-telephone-portable-est-sur-ecoute\/\" target=\"_blank\" rel=\"noopener\">appel\u00e9<\/a> quand il n&#039;\u00e9tait pas disponible\u00a0; De plus, cela permet <strong>enregistrer des messages vocaux<\/strong> que l&#039;utilisateur peut \u00e9couter quand il le peut. Et bien qu\u2019il s\u2019agisse d\u2019un outil tr\u00e8s utile dans certaines situations, il en existe de nombreux <a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-savoir-ou-se-trouve-une-personne-par-telephone-portable\/\" target=\"_blank\" rel=\"noopener\">utilisateurs<\/a> qu&#039;ils pr\u00e9f\u00e9reraient d\u00e9sactiver la messagerie vocale de Yoigo. C&#039;est pourquoi nous vous proposons ci-dessous un <strong>guide \u00e9tape par \u00e9tape pour que vous puissiez d\u00e9sactiver votre messagerie vocale <a href=\"https:\/\/miyoigo.yoigo.com\/login\" target=\"_blank\" rel=\"noopener\">yoigo<\/a><\/strong>.<\/p>\n<div class=\"lyte-wrapper fourthree\" title=\"Comment supprimer la messagerie vocale Yoigo\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_2R57wUZUzsU\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/2R57wUZUzsU\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/2R57wUZUzsU\" \/><meta itemprop=\"duration\" content=\"PT1M19S\" \/><meta itemprop=\"uploadDate\" content=\"2018-11-27T09:00:00Z\" \/><\/div><div id=\"lyte_2R57wUZUzsU\" data-src=\"https:\/\/i.ytimg.com\/vi\/2R57wUZUzsU\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Comment supprimer la messagerie vocale Yoigo<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/2R57wUZUzsU\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/2R57wUZUzsU\/0.jpg\" alt=\"Comment supprimer la messagerie vocale Yoigo\" width=\"420\" height=\"295\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Video tutorial en el que explicamos paso a paso como quitar o desactivar el buz\u00f3n de voz o el contestador que viene por defecto en nuestros tel\u00e9fono movil de la compa\u00f1\u00eda Yoigo.\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/p>\n<h2>Comment d\u00e9sactiver la messagerie vocale Yoigo<\/h2>\n<h3>Index des mati\u00e8res<\/h3>\n<ul>\n<li><a href=\"#por que\">Pourquoi supprimer la messagerie vocale Yoigo<\/a><\/li>\n<li><a href=\"#como\">Comment supprimer la messagerie vocale Yoigo<\/a><\/li>\n<li><a href=\"#volver activar\">Comment r\u00e9activer la messagerie vocale Yoigo<\/a><\/li>\n<\/ul>\n<h2><a id=\"por que\" name=\"por que\"><span style=\"color:#000000\">Pourquoi supprimer la messagerie vocale Yoigo<\/span><\/a><\/h2>\n<p>Beaucoup se demanderont pourquoi supprimer la messagerie vocale Yoigo si c&#039;est un outil tr\u00e8s utile dans de nombreuses circonstances. Et l&#039;expansion des applications de messagerie instantan\u00e9e comme <strong>WhatsApp<\/strong> soit <strong>T\u00e9l\u00e9gramme<\/strong> et m\u00eame de <strong>r\u00e9seaux sociaux<\/strong> Cela y est pour beaucoup, puisqu&#039;il permet aux utilisateurs de communiquer directement, donc un message vocal n&#039;est presque plus n\u00e9cessaire \u00e0 tout moment. Et si lorsque vous appelez quelqu&#039;un, il ne r\u00e9pond pas, le plus courant est <strong>je te laisse un SMS<\/strong> via l&#039;une de ces applications.<\/p>\n<p><img decoding=\"async\" alt=\"Comment supprimer la messagerie vocale Yoigo\" src=\"\/media\/upload\/2021\/10\/18\/como-quitar-buzon-voz-yoigo-02.jpg\" style=\"width:100%\" title=\"Comment supprimer la messagerie vocale Yoigo\"><\/p>\n<p>Une autre raison est que ce sont les contacts qui <strong>demandez-nous de d\u00e9sactiver la messagerie vocale<\/strong>, car il peut \u00eatre ennuyeux que lorsque nous ne leur r\u00e9pondons pas, un r\u00e9pondeur qu&#039;ils n&#039;utiliseront pas se d\u00e9clenche ; De plus, ce sont eux qui <strong>ils re\u00e7oivent le prix de l&#039;appel<\/strong> r\u00e9pondu par messagerie vocale, ce qui peut \u00eatre irritant.<\/p>\n<p>La derni\u00e8re raison est que si vous voyagez \u00e0 l&#039;\u00e9tranger avec la messagerie vocale activ\u00e9e, <strong>L&#039;utilisateur devra assumer le co\u00fbt de chaque appel re\u00e7u<\/strong>, en fonction du tarif de roaming de chaque zone. Pour ces raisons et d&#039;autres, vous souhaiterez peut-\u00eatre supprimer la messagerie vocale Yoigo\u00a0; Ci-dessous, nous vous proposons un guide \u00e9tape par \u00e9tape.<\/p>\n<h2><a id=\"como\" name=\"como\"><span style=\"color:#000000\">Comment supprimer la messagerie vocale Yoigo<\/span><\/a><\/h2>\n<p>Si \u00e0 ce stade vous voulez toujours <strong>d\u00e9sactiver la messagerie vocale Yoigo<\/strong>, il vous suffit de suivre les \u00e9tapes suivantes :<\/p>\n<ol>\n<li>Composez le *67*556# et appelez.<\/li>\n<li>Composez maintenant *62*556# et rappelez.<\/li>\n<li>Enfin, composez le *61*556# et appelez une derni\u00e8re fois.<\/li>\n<\/ol>\n<p>C&#039;est aussi simple que de d\u00e9sactiver la messagerie vocale Yoigo.<\/p>\n<p><img decoding=\"async\" alt=\"Comment supprimer la messagerie vocale Yoigo\" src=\"\/media\/upload\/2021\/10\/18\/como-quitar-buzon-voz-yoigo-01.jpg\" style=\"width:100%\" title=\"Comment supprimer la messagerie vocale Yoigo\"><\/p>\n<p>D&#039;autre part, vous pouvez \u00e9galement d\u00e9sactiver la messagerie vocale Yoigo via le <a href=\"https:\/\/miyoigo.yoigo.com\/login\" target=\"_blank\" rel=\"noopener\">page Web<\/a> <strong>Mon Yoigo<\/strong>. N&#039;oubliez pas que la suppression du r\u00e9pondeur activera automatiquement le <strong>notification d&#039;appel manqu\u00e9<\/strong>.<\/p>\n<h2><a id=\"volver activar\" name=\"volver activar\"><span style=\"color:#000000\">Comment r\u00e9activer la messagerie vocale Yoigo<\/span><\/a><\/h2>\n<p>Si apr\u00e8s un certain temps de d\u00e9sactivation de la messagerie vocale Yoigo, vous d\u00e9cidez que <strong>voulez-vous l&#039;activer \u00e0 nouveau<\/strong>, vous pouvez le faire quand vous le souhaitez sans probl\u00e8mes majeurs. Pour ce faire, vous devrez suivre un processus similaire au pr\u00e9c\u00e9dent, mais avec les codes d&#039;appel suivants :<\/p>\n<ol>\n<li>Composez le *67*633# et appelez.<\/li>\n<li>Composez maintenant *62*633# et rappelez.<\/li>\n<li>Enfin, composez le *61*633# et appelez une derni\u00e8re fois.<\/li>\n<\/ol>\n<p>De m\u00eame, vous pouvez r\u00e9activer la bo\u00eete aux lettres via <strong>Mon Yoigo<\/strong>.<\/p>\n<p><img decoding=\"async\" alt=\"Comment supprimer la messagerie vocale Yoigo\" src=\"\/media\/upload\/2021\/10\/18\/yt.jpg\" style=\"width:100%\" title=\"Comment supprimer la messagerie vocale Yoigo\"><\/p>\n<h2>Plus d&#039;astuces mobiles<\/h2>\n<ul>\n<li>\n<h3><a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-savoir-ou-se-trouve-une-personne-par-telephone-portable\/\" target=\"_blank\" rel=\"noopener\">Comment savoir o\u00f9 se trouve une personne par t\u00e9l\u00e9phone portable<\/a><\/h3>\n<\/li>\n<li>\n<h3><a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-nettoyer-le-haut-parleur-mobile\/\" target=\"_blank\" rel=\"noopener\">Comment nettoyer le haut-parleur mobile<\/a><\/h3>\n<\/li>\n<li>\n<h3><a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-prendre-soin-de-la-batterie-de-liphone\/\" target=\"_blank\" rel=\"noopener\">Comment prendre soin de la batterie de l&#039;iPhone<\/a><\/h3>\n<\/li>\n<li>\n<h3><a href=\"http:\/\/trucos.com\/fr\/mobiles\/comment-savoir-si-votre-telephone-portable-est-sur-ecoute\/\" target=\"_blank\" rel=\"noopener\">Comment savoir si votre t\u00e9l\u00e9phone portable est sur \u00e9coute<\/a><\/h3>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si votre r\u00e9pondeur vous g\u00eane ou vous pose probl\u00e8me, nous vous proposons la solution pour que vous puissiez le d\u00e9sactiver<\/p>","protected":false},"author":2,"featured_media":2702,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[19],"class_list":["post-2701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moviles","tag-tecnologia"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo quitar el buz\u00f3n de voz de Yoigo - Trucos.com<\/title>\n<meta name=\"description\" content=\"Si tu contestador es un incordio o te de problemas te ofrecemos la soluci\u00f3n para que puedas desactivarlo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo quitar el buz\u00f3n de voz de Yoigo - Trucos.com\" \/>\n<meta property=\"og:description\" content=\"Si tu contestador es un incordio o te de problemas te ofrecemos la soluci\u00f3n para que puedas desactivarlo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/\" \/>\n<meta property=\"og:site_name\" content=\"Trucos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trucoscom\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-18T18:43:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-03T13:59:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_quitar_buzon_voz_yoigo_00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment supprimer la messagerie vocale Yoigo - Trucos.com","description":"Si votre r\u00e9pondeur vous g\u00eane ou vous pose probl\u00e8me, nous vous proposons la solution pour que vous puissiez le d\u00e9sactiver","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00f3mo quitar el buz\u00f3n de voz de Yoigo - Trucos.com","og_description":"Si tu contestador es un incordio o te de problemas te ofrecemos la soluci\u00f3n para que puedas desactivarlo","og_url":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/","og_site_name":"Trucos.com","article_publisher":"https:\/\/www.facebook.com\/trucoscom\/","article_published_time":"2021-10-18T18:43:58+00:00","article_modified_time":"2023-08-03T13:59:29+00:00","og_image":[{"width":800,"height":606,"url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_quitar_buzon_voz_yoigo_00.jpg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redaccion","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/#article","isPartOf":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/"},"author":{"name":"Redaccion","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536"},"headline":"C\u00f3mo quitar el buz\u00f3n de voz de Yoigo","datePublished":"2021-10-18T18:43:58+00:00","dateModified":"2023-08-03T13:59:29+00:00","mainEntityOfPage":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/"},"wordCount":656,"publisher":{"@id":"https:\/\/trucos.com\/#organization"},"image":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_quitar_buzon_voz_yoigo_00.jpg","keywords":["Tecnologia"],"articleSection":["M\u00f3viles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/","url":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/","name":"Comment supprimer la messagerie vocale Yoigo - Trucos.com","isPartOf":{"@id":"https:\/\/trucos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/#primaryimage"},"image":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_quitar_buzon_voz_yoigo_00.jpg","datePublished":"2021-10-18T18:43:58+00:00","dateModified":"2023-08-03T13:59:29+00:00","description":"Si votre r\u00e9pondeur vous g\u00eane ou vous pose probl\u00e8me, nous vous proposons la solution pour que vous puissiez le d\u00e9sactiver","breadcrumb":{"@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/#primaryimage","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_quitar_buzon_voz_yoigo_00.jpg","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_quitar_buzon_voz_yoigo_00.jpg","width":800,"height":606},{"@type":"BreadcrumbList","@id":"https:\/\/trucos.com\/fr\/mobiles\/xcomment-supprimer-la-messagerie-vocale-yoigo-01-jpg-pagespeed-ic-c9bdrorwu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trucos.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo quitar el buz\u00f3n de voz de Yoigo"}]},{"@type":"WebSite","@id":"https:\/\/trucos.com\/#website","url":"https:\/\/trucos.com\/","name":"Astuces.com","description":"Les meilleures astuces sur les jeux vid\u00e9o, la technologie et les t\u00e9l\u00e9phones portables","publisher":{"@id":"https:\/\/trucos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trucos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trucos.com\/#organization","name":"Astuces.com","url":"https:\/\/trucos.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","width":207,"height":68,"caption":"Trucos.com"},"image":{"@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trucoscom\/"]},{"@type":"Person","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536","name":"Redaction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","caption":"Redaccion"},"sameAs":["http:\/\/trucos.com"],"url":"https:\/\/trucos.com\/fr\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/2701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/comments?post=2701"}],"version-history":[{"count":1,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/2701\/revisions"}],"predecessor-version":[{"id":3518,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/2701\/revisions\/3518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media\/2702"}],"wp:attachment":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media?parent=2701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/categories?post=2701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/tags?post=2701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}