{"id":2849,"date":"2022-01-29T15:09:05","date_gmt":"2022-01-29T15:09:05","guid":{"rendered":"http:\/\/trucos.com\/uncategorized\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/"},"modified":"2022-01-29T15:09:05","modified_gmt":"2022-01-29T15:09:05","slug":"comment-savoir-si-je-suis-inscrit-a-la-securite-sociale","status":"publish","type":"post","link":"https:\/\/trucos.com\/fr\/linternet\/comment-savoir-si-je-suis-inscrit-a-la-securite-sociale\/","title":{"rendered":"Comment savoir si je suis inscrit \u00e0 la S\u00e9curit\u00e9 Sociale"},"content":{"rendered":"<p>Voyons <strong>Comment savoir si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale<\/strong>, pour savoir exactement ce que vous <strong>situation du travail<\/strong> \u00e0 tout moment et toutes les donn\u00e9es associ\u00e9es dont vous avez besoin. Il s&#039;agit d&#039;un processus simple mais que tout le monde ne conna\u00eet pas, vous devez donc suivre certaines \u00e9tapes sp\u00e9cifiques tout au long du processus. <a href=\"https:\/\/sede.seg-social.gob.es\/\" target=\"_blank\" rel=\"noopener\">page Web<\/a> de la <strong>Si\u00e8ge \u00e9lectronique du <a href=\"http:\/\/trucos.com\/fr\/linternet\/comment-changer-le-numero-de-telephone-de-la-securite-sociale\/\" target=\"_blank\" rel=\"noopener\">S\u00e9curit\u00e9 sociale<\/a><\/strong>. Et m\u00eame si vous pouvez toujours demander \u00e0 votre employeur si vous \u00eates inscrit, vous pouvez v\u00e9rifier par vous-m\u00eame s&#039;il ne r\u00e9pond pas ; ou si vous \u00eates travailleur ind\u00e9pendant, pour \u00eatre s\u00fbr que vous citez correctement. Ne manquez donc pas <strong>Comment savoir si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale et quel est votre <a href=\"http:\/\/trucos.com\/fr\/linternet\/comment-telecharger-la-vie-professionnelle\/\" target=\"_blank\" rel=\"noopener\">situation du travail<\/a><\/strong>.<\/p>\n<div class=\"lyte-wrapper fourthree\" title=\"\ud83d\udd8aComment savoir si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale depuis Internet (avril 2020) - \u00c9tape par \u00e9tape\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_7ZpTnrzmlM4\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/7ZpTnrzmlM4\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/7ZpTnrzmlM4\" \/><meta itemprop=\"duration\" content=\"PT3M23S\" \/><meta itemprop=\"uploadDate\" content=\"2020-04-15T09:14:31Z\" \/><\/div><div id=\"lyte_7ZpTnrzmlM4\" data-src=\"https:\/\/i.ytimg.com\/vi\/7ZpTnrzmlM4\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">\ud83d\udd8aComment savoir si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale depuis Internet (avril 2020) - \u00c9tape par \u00e9tape<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/7ZpTnrzmlM4\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/7ZpTnrzmlM4\/0.jpg\" alt=\"\ud83d\udd8aComment savoir si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale depuis Internet (avril 2020) - \u00c9tape par \u00e9tape\" width=\"420\" height=\"295\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"Para m\u00e1s informaci\u00f3n sobre este tr\u00e1mite \ud83d\udc47 https:\/\/entretramites.com\/laboral\/como-saber-si-estas-dado-de-alta-en-la-seguridad-social Para una consulta gratis sobre tus dudas acerca de modelos y tr\u00e1mites inscr\u00edbete aqu\u00ed \ud83d\udc47 https:\/\/entretramites.com\/promociones\/30-minutos-de-asesoria-gratuita o llama aqu\u00ed \ud83d\udc47 930 185 237 En el siguiente video encontrar\u00e1s el Paso a Paso para saber tu situaci\u00f3n actual en la Seguridad Social. Esperamos te sea de gran utilidad, no dudes en escribirnos tus dudas, comentarios o compartir la informaci\u00f3n con todo el que la necesita! Si les ha gustado, no olviden los likes y suscribirse. Consulte y aprenda a solicitar desde casa los documentos m\u00e1s habituales oa solicitar las ayudas, prestaciones o informaci\u00f3n que cualquier persona necesite de las distintas Administraciones P\u00fablicas (Seguridad Social, SEPE, TGSS, INSS, Hacienda, Extranjer\u00eda, etc ). Entre Tr\u00e1mites se convierte en el portal de informaci\u00f3n desvinculado de cualquier sede electr\u00f3nica, ministerio u organismo oficial. #entretramites #RegistroClave #SistemaClave #Tr\u00e1mitesEspa\u00f1a #CartaInvitaci\u00f3n #TutorialClave #Gu\u00edaPasoAPaso #Tr\u00e1mitesOnline #RegistroClaveEspa\u00f1a #ClaveEspa\u00f1a #TutorialTr\u00e1mites\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/p>\n<h2>Comment conna\u00eetre votre situation en mati\u00e8re de s\u00e9curit\u00e9 sociale<\/h2>\n<p>Avant d&#039;entamer la d\u00e9marche en ligne pour savoir si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale, vous devez d&#039;abord savoir que dans tous les bureaux de la <strong>Tr\u00e9sorerie G\u00e9n\u00e9rale de la S\u00e9curit\u00e9 Sociale<\/strong> Ils sont tenus de vous fournir ces informations ; Oui, vous devrez d&#039;abord appeler au <strong>prendre rendez-vous<\/strong>. Par cons\u00e9quent, si vous en avez besoin <a href=\"http:\/\/trucos.com\/fr\/linternet\/comment-obtenir-un-numero-de-securite-sociale\/\" target=\"_blank\" rel=\"noopener\">information<\/a> le plus t\u00f4t possible et sans avoir \u00e0 attendre votre employeur ou \u00e0 vous rendre dans un bureau, ne manquez pas comment conna\u00eetre votre situation professionnelle via Internet, pour laquelle vous aurez besoin de votre <strong>certificat num\u00e9rique<\/strong> ou toi <strong><a href=\"http:\/\/trucos.com\/fr\/linternet\/systeme-de-cles-comment-sinscrire-et-effectuer-les-procedures-fiscales\/\" target=\"_blank\" rel=\"noopener\">Code PIN Cl@ve<\/a><\/strong> \u00e0 identifier et \u00e0 acc\u00e9der.<\/p>\n<p><img decoding=\"async\" alt=\"Comment savoir si je suis inscrit \u00e0 la S\u00e9curit\u00e9 Sociale\" src=\"\/media\/upload\/2022\/01\/29\/como-saber-si-estas-dado-de-alta-seguridad-social-01.jpg\" style=\"width:100%\" title=\"Comment savoir si je suis inscrit \u00e0 la S\u00e9curit\u00e9 Sociale\" \/><\/p>\n<p>Suivez les \u00e9tapes ci-dessous pour <strong>savoir si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale<\/strong>:<\/p>\n<ol>\n<li>La premi\u00e8re \u00e9tape consiste \u00e0 acc\u00e9der au site Internet du <strong>Si\u00e8ge \u00e9lectronique de la S\u00e9curit\u00e9 Sociale<\/strong> (<a href=\"https:\/\/sede.seg-social.gob.es\/\" target=\"_blank\" rel=\"noopener\">si\u00e8ge social.seg-social.gob.es<\/a>).<\/li>\n<li>Une fois \u00e0 l&#039;int\u00e9rieur, cliquez sur la section <strong>Rapports et certificats<\/strong> dans l&#039;onglet <strong>Citoyens<\/strong>.<\/li>\n<li>Maintenant cherche l&#039;entr\u00e9e <strong>Rapport sur la situation actuelle du travailleur<\/strong>.<\/li>\n<li>Un menu s&#039;ouvrira avec <strong>Acc\u00e8s direct aux proc\u00e9dures<\/strong>.<\/li>\n<li>Choisissez maintenant la m\u00e9thode pour v\u00e9rifier votre identit\u00e9 (<strong>certificat num\u00e9rique<\/strong> soit <strong>Code PIN Cl@ve<\/strong>).<\/li>\n<li>Lorsque vous choisissez l&#039;une des deux m\u00e9thodes, une fen\u00eatre s&#039;ouvrira pour confirmer la m\u00e9thode d&#039;identification.<\/li>\n<li>Une fois votre identit\u00e9 v\u00e9rifi\u00e9e, vous pouvez cliquer sur le <strong>ic\u00f4ne de l&#039;imprimante<\/strong> pour imprimer le rapport de votre situation d&#039;emploi au m\u00eame moment ou cliquez sur le bouton <strong>Cliquez ici pour ouvrir le rapport<\/strong> pour le visualiser \u00e0 l&#039;\u00e9cran.<\/li>\n<li>Le rapport sur votre situation professionnelle actuelle s&#039;ouvrira dans votre navigateur, avec vos donn\u00e9es personnelles et votre situation en bas.<\/li>\n<\/ol>\n<p><img decoding=\"async\" alt=\"Comment savoir si je suis inscrit \u00e0 la S\u00e9curit\u00e9 Sociale\" src=\"\/media\/upload\/2022\/01\/29\/como-saber-si-estas-dado-de-alta-seguridad-social-02.jpg\" style=\"width:100%\" title=\"Comment savoir si je suis inscrit \u00e0 la S\u00e9curit\u00e9 Sociale\" \/><\/p>\n<p>Dans la colonne intitul\u00e9e <strong>Situation<\/strong> Il appara\u00eetra si vous \u00eates inscrit ou non et \u00e0 droite la date depuis votre inscription \u00e0 la S\u00e9curit\u00e9 Sociale. Dans le m\u00eame rapport, vous pourrez voir votre <strong>r\u00e9gime<\/strong>, si vous \u00eates ind\u00e9pendant ou embauch\u00e9 en tant que salari\u00e9, ou l&#039;entreprise ou le statut d&#039;enregistrement.<\/p>\n<p>Maintenant tu sais <strong>Comment savoir si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale <\/strong>et quelle est votre situation d&#039;emploi en quelques \u00e9tapes simples en ligne.<\/p>\n<p><img decoding=\"async\" alt=\"Comment savoir si je suis inscrit \u00e0 la S\u00e9curit\u00e9 Sociale\" src=\"\/media\/upload\/2022\/01\/29\/como-saber-si-estas-dado-de-alta-seguridad-social-03.jpg\" style=\"width:100%\" title=\"Comment savoir si je suis inscrit \u00e0 la S\u00e9curit\u00e9 Sociale\" \/><\/p>\n<h2>Plus de conseils de gestion<\/h2>\n<ul>\n<li>\n<h3><a href=\"http:\/\/trucos.com\/fr\/linternet\/comment-obtenir-un-numero-de-securite-sociale\/\" target=\"_blank\" rel=\"noopener\">Comment obtenir le num\u00e9ro de s\u00e9curit\u00e9 sociale<\/a><\/h3>\n<\/li>\n<li>\n<h3><a href=\"http:\/\/trucos.com\/fr\/linternet\/comment-changer-le-numero-de-telephone-de-la-securite-sociale\/\" target=\"_blank\" rel=\"noopener\">Comment changer le num\u00e9ro de t\u00e9l\u00e9phone de la s\u00e9curit\u00e9 sociale<\/a><\/h3>\n<\/li>\n<li>\n<h3><a href=\"http:\/\/trucos.com\/fr\/linternet\/comment-telecharger-la-vie-professionnelle\/\" target=\"_blank\" rel=\"noopener\">Comment t\u00e9l\u00e9charger la vie professionnelle<\/a><\/h3>\n<\/li>\n<li>\n<h3><a href=\"http:\/\/trucos.com\/fr\/linternet\/systeme-de-cles-comment-sinscrire-et-effectuer-les-procedures-fiscales\/\" target=\"_blank\" rel=\"noopener\">Cl@ve System : comment enregistrer et effectuer les proc\u00e9dures de Tr\u00e9sorerie<\/a><\/h3>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez \u00e0 tout moment si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale et quelle est votre situation professionnelle, en quelques \u00e9tapes en ligne<\/p>","protected":false},"author":2,"featured_media":2850,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[19],"class_list":["post-2849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet","tag-tecnologia"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo saber si estoy dado de alta en la Seguridad Social - Trucos.com<\/title>\n<meta name=\"description\" content=\"Descubre si est\u00e1s dado de alta en la Seguridad Social y cu\u00e1l es tu situaci\u00f3n laboral en todo momento, todo ello a trav\u00e9s de unos pocos pasos online\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trucos.com\/fr\/linternet\/comment-savoir-si-je-suis-inscrit-a-la-securite-sociale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo saber si estoy dado de alta en la Seguridad Social - Trucos.com\" \/>\n<meta property=\"og:description\" content=\"Descubre si est\u00e1s dado de alta en la Seguridad Social y cu\u00e1l es tu situaci\u00f3n laboral en todo momento, todo ello a trav\u00e9s de unos pocos pasos online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trucos.com\/fr\/linternet\/comment-savoir-si-je-suis-inscrit-a-la-securite-sociale\/\" \/>\n<meta property=\"og:site_name\" content=\"Trucos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trucoscom\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-29T15:09:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_saber_si_estas_dado_de_alta_seguridad_social_00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment savoir si je suis inscrit \u00e0 la S\u00e9curit\u00e9 Sociale - Trucos.com","description":"D\u00e9couvrez \u00e0 tout moment si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale et quelle est votre situation professionnelle, en quelques \u00e9tapes en ligne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trucos.com\/fr\/linternet\/comment-savoir-si-je-suis-inscrit-a-la-securite-sociale\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00f3mo saber si estoy dado de alta en la Seguridad Social - Trucos.com","og_description":"Descubre si est\u00e1s dado de alta en la Seguridad Social y cu\u00e1l es tu situaci\u00f3n laboral en todo momento, todo ello a trav\u00e9s de unos pocos pasos online","og_url":"https:\/\/trucos.com\/fr\/linternet\/comment-savoir-si-je-suis-inscrit-a-la-securite-sociale\/","og_site_name":"Trucos.com","article_publisher":"https:\/\/www.facebook.com\/trucoscom\/","article_published_time":"2022-01-29T15:09:05+00:00","og_image":[{"width":800,"height":548,"url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_saber_si_estas_dado_de_alta_seguridad_social_00.jpg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redaccion","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/#article","isPartOf":{"@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/"},"author":{"name":"Redaccion","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536"},"headline":"C\u00f3mo saber si estoy dado de alta en la Seguridad Social","datePublished":"2022-01-29T15:09:05+00:00","mainEntityOfPage":{"@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/"},"wordCount":668,"publisher":{"@id":"https:\/\/trucos.com\/#organization"},"image":{"@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_saber_si_estas_dado_de_alta_seguridad_social_00.jpg","keywords":["Tecnologia"],"articleSection":["Internet"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/","url":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/","name":"Comment savoir si je suis inscrit \u00e0 la S\u00e9curit\u00e9 Sociale - Trucos.com","isPartOf":{"@id":"https:\/\/trucos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/#primaryimage"},"image":{"@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_saber_si_estas_dado_de_alta_seguridad_social_00.jpg","datePublished":"2022-01-29T15:09:05+00:00","description":"D\u00e9couvrez \u00e0 tout moment si vous \u00eates inscrit \u00e0 la S\u00e9curit\u00e9 Sociale et quelle est votre situation professionnelle, en quelques \u00e9tapes en ligne","breadcrumb":{"@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/#primaryimage","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_saber_si_estas_dado_de_alta_seguridad_social_00.jpg","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/como_saber_si_estas_dado_de_alta_seguridad_social_00.jpg","width":800,"height":548},{"@type":"BreadcrumbList","@id":"https:\/\/trucos.com\/internet\/como-saber-si-estoy-dado-de-alta-en-la-seguridad-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trucos.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo saber si estoy dado de alta en la Seguridad Social"}]},{"@type":"WebSite","@id":"https:\/\/trucos.com\/#website","url":"https:\/\/trucos.com\/","name":"Astuces.com","description":"Les meilleures astuces sur les jeux vid\u00e9o, la technologie et les t\u00e9l\u00e9phones portables","publisher":{"@id":"https:\/\/trucos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trucos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trucos.com\/#organization","name":"Astuces.com","url":"https:\/\/trucos.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","width":207,"height":68,"caption":"Trucos.com"},"image":{"@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trucoscom\/"]},{"@type":"Person","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536","name":"Redaction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","caption":"Redaccion"},"sameAs":["http:\/\/trucos.com"],"url":"https:\/\/trucos.com\/fr\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/2849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/comments?post=2849"}],"version-history":[{"count":0,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/2849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media\/2850"}],"wp:attachment":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media?parent=2849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/categories?post=2849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/tags?post=2849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}