{"id":470,"date":"2016-09-26T16:33:54","date_gmt":"2016-09-26T16:33:54","guid":{"rendered":"http:\/\/trucos.com\/uncategorized\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/"},"modified":"2016-09-26T16:33:54","modified_gmt":"2016-09-26T16:33:54","slug":"resident-evil-hd-astuces-pour-ps3-ps4-pc-xbox-360-xbox-one","status":"publish","type":"post","link":"https:\/\/trucos.com\/fr\/jeux-video\/resident-evil-hd-astuces-pour-ps3-ps4-pc-xbox-360-xbox-one\/","title":{"rendered":"Astuces Resident Evil HD pour PS3, PS4, PC, Xbox 360, Xbox One"},"content":{"rendered":"<p>Visitez \u00e0 nouveau le manoir dans <a href=\"http:\/\/www.capcom.co.jp\/biohd\/\" title=\"Page officielle de Resident Evil\">Resident Evil HD<\/a>.<\/p>\n<h2>Plantes m\u00e9dicinales<\/h2>\n<p>Les pots que vous trouverez peuvent \u00eatre de trois couleurs. Apprenez leurs effets le plus t\u00f4t possible car ils sont le moyen de survivre dans le jeu, les sprays curatifs sont tr\u00e8s rares. En r\u00e8gle g\u00e9n\u00e9rale, vous ne pouvez pas m\u00e9langer plus d\u2019une plante bleue ou rouge dans une combinaison, et vous ne pouvez pas ajouter une plante rouge ou bleue \u00e0 deux plantes vertes.<\/p>\n<ul>\n<li><strong>Vert<\/strong>- Gu\u00e9rit la sant\u00e9 de 25%<\/li>\n<li><strong>Vert + vert<\/strong>- Gu\u00e9rit la sant\u00e9 de 60%<\/li>\n<li><strong>Vert + vert + vert<\/strong>: gu\u00e9rit 100%<\/li>\n<li><strong>Vert + rouge<\/strong>: gu\u00e9rit 100%<\/li>\n<li><strong>Vert + bleu<\/strong>: gu\u00e9rit le 25% et le poison<\/li>\n<li><strong>Vert + vert + bleu<\/strong>: gu\u00e9rit le 60% et le poison<\/li>\n<li><strong>Vert + rouge + bleu<\/strong>: gu\u00e9rit le 100% et le poison<\/li>\n<\/ul>\n<h2>Tenues \u00e0 d\u00e9bloquer<\/h2>\n<ul>\n<li><span style=\"font-size:18px\"><strong>Inspir\u00e9 par Sarah Connor (Terminator 2) \u2013&nbsp;<\/strong>Terminez le jeu deux fois avec Jill dans n&#039;importe quelle difficult\u00e9.<\/span><\/li>\n<li><span style=\"font-size:18px\"><strong>R\u00e9sident Mal 3 \u2013&nbsp;<\/strong>Terminez le jeu deux fois dans n&#039;importe quelle difficult\u00e9 avec Jill.<\/span><\/li>\n<li><span style=\"font-size:18px\"><strong>Le Mexicain \u2013&nbsp;<\/strong>Terminez le jeu avec Chris dans n&#039;importe quelle difficult\u00e9.<\/span><\/li>\n<li><span style=\"font-size:18px\"><strong>Code V\u00e9ronique \u2013&nbsp;<\/strong>Terminez le jeu deux fois avec Chris dans n&#039;importe quelle difficult\u00e9.<\/span><\/li>\n<\/ul>\n<h2>Modes d\u00e9verrouillables<\/h2>\n<ul>\n<li><span style=\"font-size:18px\"><strong>V\u00e9ritable survivant \u2013&nbsp;<\/strong>Terminez le jeu normalement<\/span><\/li>\n<li><span style=\"font-size:18px\"><strong>ennemi invisible \u2013&nbsp;<\/strong>Fin du vrai survivant<\/span><\/li>\n<li><span style=\"font-size:18px\"><strong>Encore une fois\u2026 -&nbsp;<\/strong>Terminez le jeu une fois dans n&#039;importe quelle difficult\u00e9<\/span><\/li>\n<li><span style=\"font-size:18px\"><strong>Un zombie dangereux \u2013&nbsp;<\/strong>Terminez le jeu avec Chris et Jill en mode normal ou sup\u00e9rieur avec le m\u00eame fichier de sauvegarde.<\/span><\/li>\n<\/ul>\n<h2>Armes d\u00e9verrouillables<\/h2>\n<p><strong>Bord de samoura\u00ef \u2013&nbsp;<\/strong>Terminez le jeu en mode Normal ou Difficile en cinq heures ou moins.<\/p>\n<p><strong>Lance-roquettes Infinity \u2013&nbsp;<\/strong>Terminez le jeu en mode Normal ou Difficile en trois heures ou moins.<\/p>\n<h2>Message secret<\/h2>\n<p>Terminez le jeu en mode furtif en moins de cinq heures. Vous d\u00e9bloquerez un message secret de Shinji Mikami, r\u00e9alisateur du remake et cr\u00e9ateur de Resident Evil, ainsi qu&#039;une galerie de costumes abandonn\u00e9s pour les protagonistes.<\/p>\n<h2>Astuces Resident Evil HD pour PC<\/h2>\n<p>Nous vous laissons une vid\u00e9o int\u00e9ressante pour activer diverses astuces sur PC. On peut mettre des munitions infinies, une vie infinie, obtenir toutes les cl\u00e9s, etc.<\/p>\n<div style=\"position: relative; width: 100%; height: 0px; padding-bottom: 60%;\"><div class=\"lyte-wrapper fourthree\" title=\"RESIDENT EVIL REFAIRE HD | ASTUCES POUR PC\" style=\"width:420px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_FkheHfU42Ak\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/FkheHfU42Ak\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/FkheHfU42Ak\" \/><meta itemprop=\"duration\" content=\"PT15M50S\" \/><meta itemprop=\"uploadDate\" content=\"2015-03-02T16:10:03Z\" \/><\/div><div id=\"lyte_FkheHfU42Ak\" data-src=\"https:\/\/i.ytimg.com\/vi\/FkheHfU42Ak\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">RESIDENT EVIL REFAIRE HD | ASTUCES POUR PC<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/FkheHfU42Ak\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/FkheHfU42Ak\/0.jpg\" alt=\"RESIDENT EVIL REFAIRE HD | ASTUCES POUR PC\" width=\"420\" height=\"295\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"LINK DEL PROGRAMA ABAJO: \u00a1Hola polaquitos!, aqu\u00ed os traemos un v\u00eddeo algo especial, ya que no nos dedicamos a este tipo de cosas, pero nos ha llamado tanto la atenci\u00f3n que hemos querido compartirlo. \u00a1Esperamos que os guste!. :D Link del programa: http:\/\/yellotrainer.net\/?p=336\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px auto;\"><\/div><\/div>\n<p>&nbsp;<\/p>\n<h2>R\u00e9alisations\/Troph\u00e9es<\/h2>\n<p><strong>Pas une \u00e9gratignure.<\/strong><br \/>\n<em>Terminez le jeu en difficult\u00e9 Tr\u00e8s facile ou sup\u00e9rieure.<\/em><br \/>\nTerminez l&#039;aventure en difficult\u00e9 Tr\u00e8s Facile, Facile ou Normal.<\/p>\n<p><strong>Blessures mineures.<\/strong><br \/>\n<em>Terminez le jeu en difficult\u00e9 facile ou sup\u00e9rieure.<\/em><br \/>\nTerminez le mode histoire en difficult\u00e9 facile ou normale.<\/p>\n<p><strong>Sang, sueur et vice versa.<\/strong><br \/>\n<em>Terminez le jeu en mode normal ou sup\u00e9rieur.<\/em><br \/>\nEn fait, il s&#039;agit de terminer l&#039;aventure en mode normal.<\/p>\n<p><strong>Voler les morts ?<\/strong><br \/>\n<em>R\u00e9cup\u00e9rez l&#039;objet en pierre et en m\u00e9tal avec Chris.<\/em><br \/>\nIl fait r\u00e9f\u00e9rence \u00e0 l&#039;objet hexagonal que vous retrouverez tout au long de l&#039;aventure. Le processus avec Chris est un peu plus complexe. Faites-le et vous obtiendrez le troph\u00e9e.<\/p>\n<p><strong>Jardinage \u00e0 haut risque.<\/strong><br \/>\n<em>Battez l&#039;usine 42 avec Chris.<\/em><br \/>\nDans le chapitre \u00ab La Plante Damn\u00e9e \u00bb, vous devrez tuer une \u00e9norme plante qui vous bloquera le passage. Faites-le avec Chris pour le d\u00e9bloquer.<\/p>\n<p><strong>Collection compl\u00e8te.<\/strong><br \/>\n<em>Obtenez le tome 2 avec Chris.<\/em><br \/>\nIl fait r\u00e9f\u00e9rence au volume du journal du scientifique Umbrella. Si vous r\u00e9cup\u00e9rez toutes les cl\u00e9s, lors de la derni\u00e8re inspection, vous devriez les trouver au 2F.<\/p>\n<p><strong>R\u00e9union familiale.<\/strong><br \/>\nBattez Lisa Trevor avec Chris.<\/p>\n<p><strong>Exhum\u00e9.<\/strong><br \/>\n<em>Battez un prototype Crimson Head 1 avec Jill.<\/em><br \/>\nDans le guide, nous l&#039;avons appel\u00e9 \u00ab Big Crimson Head \u00bb, mais c&#039;est la m\u00eame chose. C&#039;est la cr\u00e9ature qui se trouve dans le tombeau suspendu de la crypte.<\/p>\n<p><strong>Gouvernante.<\/strong><br \/>\n<em>Obtenez la cl\u00e9 du casque aupr\u00e8s de Jill.<\/em><br \/>\nD\u00e9blocable tout au long de l&#039;aventure.<\/p>\n<p><strong>Chasseur de monstre.<\/strong><br \/>\n<em>Battez Yawn avec Jill.<\/em><br \/>\nTuez le serpent g\u00e9ant dans le r\u00f4le de Jill.<\/p>\n<p><strong>\u00c0 la recherche de la v\u00e9rit\u00e9.<\/strong><br \/>\n<em>Parvenez \u00e0 entrer dans le laboratoire en tant que Jill.<\/em><br \/>\nDans la derni\u00e8re partie de l&#039;aventure, vous pourrez entrer dans le laboratoire secret d&#039;Umbrella dont l&#039;acc\u00e8s se fait par l&#039;escalier arri\u00e8re du hall. Faites comme Jill et le troph\u00e9e sera \u00e0 vous.<\/p>\n<p><strong>C&#039;est Resident Evil.<\/strong><br \/>\n<em>Meurs pour la premi\u00e8re fois.<\/em><br \/>\nVous n&#039;aurez aucun probl\u00e8me \u00e0 l&#039;obtenir...<\/p>\n<p><strong>\u00c7a sent le steak.<\/strong><br \/>\n<em>Br\u00fblez un zombie.<\/em><br \/>\nPrenez le r\u00e9cipient de k\u00e9ros\u00e8ne, versez-le sur un zombie et br\u00fblez-le avec le briquet pour qu&#039;il ne se rel\u00e8ve plus.<\/p>\n<p><strong>Chasseur traqu\u00e9.<\/strong><br \/>\n<em>Battez un chasseur.<\/em><br \/>\nD\u00e9blocable tout au long de l&#039;aventure.<\/p>\n<p><strong>Bravo, R\u00e9becca, Bravo.<\/strong><br \/>\n<em>Sauvez Chris avec Rebecca.<\/em><br \/>\nD\u00e9blocable dans l&#039;aventure de Chris.<\/p>\n<p><strong>Quelle noblesse.<\/strong><br \/>\n<em>Sauvez Jill avec Barry.<\/em><br \/>\nD\u00e9blocable dans l&#039;aventure de Jill.<\/p>\n<p><strong>Retarder l&#039;in\u00e9vitable.<\/strong><br \/>\n<em>Sauvez Richard \u00e0 l&#039;aide d&#039;un s\u00e9rum.<\/em><br \/>\nLorsque Richard vous demandera de trouver le s\u00e9rum pour le sauver de la morsure de Yawn, vous devrez vite aller le chercher et revenir. Si vous tardez trop, Richard mourra et vous ne pourrez pas obtenir le troph\u00e9e.<\/p>\n<p><strong>Punis sans d\u00eener.<\/strong><br \/>\n<em>Sauvez Rebecca du chasseur.<\/em><br \/>\nDans l&#039;aventure de Chris, il y a un moment o\u00f9 vous pouvez sauver Rebecca en lui d\u00e9barrassant le Monster Hunter de son dos. Faites-le et vous l&#039;obtiendrez.<\/p>\n<p><strong>Chanceux Trevor.<\/strong><br \/>\n<em>Sauvez Barry de Lisa Trevor.<\/em><br \/>\nD\u00e9blocable dans l&#039;aventure de Jill.<\/p>\n<p><strong>Que ferais-tu sans moi ?<\/strong><br \/>\n<em>Lib\u00e9rez Jill de sa captivit\u00e9 avec Chris.<\/em><\/p>\n<p><strong>Dois-je tout faire ?<\/strong><br \/>\n<em>Lib\u00e9rez Chris de sa captivit\u00e9 avec Jill.<\/em><\/p>\n<p><strong>Pourquoi ne meurs-tu pas ?<\/strong><br \/>\n<em>Battez une t\u00eate cramoisie.<\/em><\/p>\n<p><strong>Pour les cheveux\u2026<\/strong><br \/>\n<em>Survivez \u00e0 la premi\u00e8re attaque de Yawn.<\/em><br \/>\nLorsque le serpent g\u00e9ant Yawn appara\u00eet, vous devez choisir de ne pas le tuer d\u00e8s le premier affrontement, mais plut\u00f4t de le faire fuir. Prenez le masque et quittez la pi\u00e8ce pour r\u00e9cup\u00e9rer le troph\u00e9e.<\/p>\n<p><strong>Requin frit !<\/strong><br \/>\n<em>Battez Neptune.<\/em><br \/>\nA l&#039;ext\u00e9rieur du manoir, lorsque le requin g\u00e9ant vous attaque, \u00e9loignez-vous de lui pour l&#039;attraper.<\/p>\n<p><strong>Sens de l&#039;araign\u00e9e.<\/strong><br \/>\n<em>Battez le Tigre Noir.<\/em><br \/>\nTuez l&#039;araign\u00e9e g\u00e9ante tout au long de l&#039;aventure.<\/p>\n<p><strong>Et sans payer un centime.<\/strong><br \/>\n<em>Obtenez toutes les tenues.<\/em><br \/>\nD\u00e9verrouillable en obtenant toutes les cl\u00e9s, ce qui vous donne acc\u00e8s \u00e0 toutes les pi\u00e8ces du manoir. Ouvrez-les tous pour augmenter votre garde-robe et obtenir le troph\u00e9e.<\/p>\n<p><strong>Comme la paume de ma main.<\/strong><br \/>\n<em>Visitez tous les sites sur toutes les cartes.<\/em><br \/>\nEntrez dans toutes les pi\u00e8ces du manoir et de la crypte, des abords, de l&#039;abri de jardin, de la maison d&#039;amis et du laboratoire.<\/p>\n<p><strong>La fin du cauchemar.<\/strong><br \/>\n<em>Terminez le jeu en difficult\u00e9 Difficile.<\/em><br \/>\nTerminez le jeu en difficult\u00e9 difficile pour l&#039;obtenir.<\/p>\n<p><strong>Nous sommes dans le m\u00eame bateau.<\/strong><br \/>\n<em>Terminez le jeu avec Jill et Chris.<\/em><br \/>\nTerminez le jeu avec les deux protagonistes. Il existe des domaines cl\u00e9s dans lesquels les itin\u00e9raires ou les actions \u00e0 mener sont diff\u00e9rents. Les \u00e9carts les plus notables entre une campagne et une autre sont indiqu\u00e9s dans les chapitres respectifs.<\/p>\n<p><strong>Horreur de survie.<\/strong><br \/>\n<em>Terminez le jeu en mode Survie.<\/em><br \/>\nD\u00e9blocable apr\u00e8s avoir termin\u00e9 le jeu en mode difficile. Terminez Survie pour d\u00e9bloquer le mode \u00ab\u00a0Ennemi invisible\u00a0\u00bb.<\/p>\n<p><strong>La premi\u00e8re fois de Chris.<\/strong><br \/>\n<em>Terminez le jeu avec Chris.<\/em><br \/>\nTerminez l&#039;aventure avec Chris Redfield.<\/p>\n<p><strong>Premi\u00e8re fois avec Jill.<\/strong><br \/>\n<em>Terminez le jeu avec Jill.<\/em><br \/>\nTerminez l&#039;aventure avec Jill Valentine.<\/p>\n<p><strong>Ce devait \u00eatre Chris.<\/strong><br \/>\n<em>Terminez le jeu avec Chris en sauvant Rebecca et Jill.<\/em><br \/>\n\u00c0 certains moments, vous pourrez sauver votre compagne disparue Jill et l&#039;innocente Rebecca. Faites-le pour l&#039;obtenir.<\/p>\n<p><strong>Ce devait \u00eatre Jill.<\/strong><br \/>\n<em>Terminez le jeu avec Jill en sauvant Chris et Barry.<\/em><br \/>\n\u00c0 certains moments, vous pourrez sauver votre partenaire disparu Chris et Barry Burton, membre de STARS. Faites-le et le troph\u00e9e sera \u00e0 vous.<\/p>\n<p><strong>Ne nous quitte pas, Chris !<\/strong><br \/>\n<em>Terminez le jeu avec Chris sans sauver personne.<\/em><br \/>\nAllez \u00e0 votre rythme tout au long de l&#039;aventure et ne sauvez pas vos compagnons.<\/p>\n<p><strong>NE nous quittez pas, Jill\u00a0!<\/strong><br \/>\n<em>Terminez le jeu avec Jill sans sauver personne.<\/em><br \/>\nNe sortez pas Chris de sa cellule et n&#039;arrivez pas \u00e0 temps pour sauver Barry et le d\u00e9bloquer.<\/p>\n<p><strong>En moins qu&#039;un Zombie chante.<\/strong><br \/>\n<em>Terminez le jeu en trois heures.<\/em><br \/>\nLe troph\u00e9e le plus difficile de tout le jeu. Il est conseill\u00e9 d&#039;aller directement aux objectifs sans s&#039;arr\u00eater pour inspecter. Profitez des munitions dans les \u00ab saverooms \u00bb et rien d\u2019autre. Oh, et simplifiez-vous les choses\u2026<\/p>\n<p><strong>Je suis un peu press\u00e9.<\/strong><br \/>\n<em>Terminez le jeu en cinq heures.<\/em><br \/>\nCompliqu\u00e9 aussi, mais si vous parvenez \u00e0 le terminer en trois, vous avez r\u00e9ussi celui-ci. Il faut conna\u00eetre par c\u0153ur l\u2019emplacement des chambres. Heureusement, le mode pause ne prend pas de temps.<\/p>\n<p><strong>Le bord de l&#039;impossible.<\/strong><br \/>\n<em>Terminez le jeu avec seulement le couteau. (Pas de briquets, d&#039;objets d\u00e9fensifs ou de marcher sur des zombies).<\/em><br \/>\nAppuyez sur le bouton L1 + le bouton R1 avec le couteau s\u00e9lectionn\u00e9 et n&#039;utilisez aucune autre arme. Surmonter les confrontations sans poignards ni Tasers va \u00eatre difficile, surtout avec les chiens, alors soyez prudent.<\/p>\n<p><strong>L\u2019\u00e9pargne est pour les l\u00e2ches.<\/strong><br \/>\n<em>Terminez le jeu sans sauvegarder.<\/em><br \/>\nIl est recommand\u00e9 de ne pas le faire dans le m\u00eame jeu que celui que vous utilisez pour terminer le jeu en trois ou cinq heures. Bien s\u00fbr, il n\u2019y a pas de lueur d\u2019espoir, vous gagnez donc de l\u2019espace dans votre inventaire dont vous devez profiter co\u00fbte que co\u00fbte pour les produits m\u00e9dicaux. Chris l&#039;appr\u00e9ciera.<\/p>\n<p><strong>Barbecue!<\/strong><br \/>\n<em>Br\u00fblez deux zombies en m\u00eame temps avec le briquet.<\/em><br \/>\nLorsque plusieurs cr\u00e9atures vous attaquent, mettez-les KO et, si elles gisent au sol \u00e0 proximit\u00e9, br\u00fbler l&#039;une incin\u00e9rera \u00e9galement l&#039;autre.<\/p>\n<p><strong>Arm\u00e9 jusqu\u2019aux dents.<\/strong><br \/>\n<em>R\u00e9cup\u00e9rez toutes les armes (y compris toutes les munitions du lance-grenades).<\/em><br \/>\nVous retrouverez toutes les armes tout au long de l&#039;aventure, \u00e0 l&#039;exception du Colt, que vous obtiendrez si vous battez la Big Crimson Head avec un 75% de sant\u00e9 pr\u00e9serv\u00e9e (dans le jeu original il fallait trouver quelques embl\u00e8mes pour l&#039;obtenir). En incarnant Jill, les munitions du lance-grenades vous seront donn\u00e9es par Barry, alors ne vous inqui\u00e9tez pas. Bien entendu, sauvez Barry pour qu&#039;il puisse vous donner tous les projectiles tout au long de la partie.<\/p>\n<p>Guide complet pour Resident Evil HD en cliquant <a href=\"http:\/\/www.meristation.com\/playstation-3\/resident-evil-hd-remaster\/guia\/1998395\/2036975\" title=\"Guide Resident Evil HD\">ici<\/a>.<\/p>\n<p><strong>Cela peut vous int\u00e9resser :<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/resident-evil-3-nemesis-solution-puzzles-re3-psx-pc-ps4-xbox-one\/\">Resident Evil 3 Nemesis, solution aux \u00e9nigmes de RE3 sur PSX, PC, PS4 et XBox One<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/astuces-resident-evil-2-remake-pour-ps4-xbox-one-et-pc\/\">Astuces Resident Evil 2 Remake pour PS4, Xbox One et PC<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/astuces-resident-evil-2-pour-ps2-pc-dreamcast-gamecube-psn-nintendo-64\/\">Astuces Resident Evil 2 pour PS2, PC, Dreamcast, Gamecube, PSN, Nintendo 64<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/resident-evil-revelations-2-astuces-pour-ps4-pc-xboxone\/\">Resident Evil Revelations 2 Astuces pour PS3, PS4, PC, Xbox 360, Xbox One<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/guide-pour-jouer-a-resident-evil-7-sur-nintendo-switch-en-espagnol\/\">Guide pour jouer \u00e0 Resident Evil 7 sur Nintendo Switch en espagnol<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/resident-evil-7-astuces-pour-ps4-pc-xbox-one\/\">Astuces Resident Evil 7 pour PS4, PC, Xbox One<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/astuces-resident-evil-revelations-pour-ps3-pc-wii-u-3ds-xbox-360\/\">Astuces Resident Evil Revelations pour PS3, PC, Wii U, 3DS, Xbox 360<\/a><\/li>\n<li><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/astuces-resident-evil-code-veronica-pour-dc-gc-ps2-ps3-xbox-360-pc\/\">Astuces Resident Evil\u00a0: Code Veronica pour DC, GC, PS2, PS3, Xbox 360, PC<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Tous les trucs, astuces et \u00e9l\u00e9ments \u00e0 d\u00e9bloquer de Resident Evil HD<\/p>","protected":false},"author":2,"featured_media":471,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[70],"class_list":["post-470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videojuegos","tag-ocio"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trucos Resident Evil HD para PS3, PS4, PC, Xbox 360, Xbox One - Trucos.com<\/title>\n<meta name=\"description\" content=\"Todos los trucos, cheats y desbloqueables de Resident Evil HD\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trucos.com\/fr\/jeux-video\/resident-evil-hd-astuces-pour-ps3-ps4-pc-xbox-360-xbox-one\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trucos Resident Evil HD para PS3, PS4, PC, Xbox 360, Xbox One - Trucos.com\" \/>\n<meta property=\"og:description\" content=\"Todos los trucos, cheats y desbloqueables de Resident Evil HD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trucos.com\/fr\/jeux-video\/resident-evil-hd-astuces-pour-ps3-ps4-pc-xbox-360-xbox-one\/\" \/>\n<meta property=\"og:site_name\" content=\"Trucos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trucoscom\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-26T16:33:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/resident-evil_600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Astuces Resident Evil HD pour PS3, PS4, PC, Xbox 360, Xbox One - Trucos.com","description":"Tous les trucs, astuces et \u00e9l\u00e9ments \u00e0 d\u00e9bloquer de Resident Evil HD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trucos.com\/fr\/jeux-video\/resident-evil-hd-astuces-pour-ps3-ps4-pc-xbox-360-xbox-one\/","og_locale":"fr_FR","og_type":"article","og_title":"Trucos Resident Evil HD para PS3, PS4, PC, Xbox 360, Xbox One - Trucos.com","og_description":"Todos los trucos, cheats y desbloqueables de Resident Evil HD","og_url":"https:\/\/trucos.com\/fr\/jeux-video\/resident-evil-hd-astuces-pour-ps3-ps4-pc-xbox-360-xbox-one\/","og_site_name":"Trucos.com","article_publisher":"https:\/\/www.facebook.com\/trucoscom\/","article_published_time":"2016-09-26T16:33:54+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/resident-evil_600.jpg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redaccion","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/#article","isPartOf":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/"},"author":{"name":"Redaccion","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536"},"headline":"Trucos Resident Evil HD para PS3, PS4, PC, Xbox 360, Xbox One","datePublished":"2016-09-26T16:33:54+00:00","mainEntityOfPage":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/"},"wordCount":1917,"publisher":{"@id":"https:\/\/trucos.com\/#organization"},"image":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/resident-evil_600.jpg","keywords":["Ocio"],"articleSection":["Videojuegos"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/","url":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/","name":"Astuces Resident Evil HD pour PS3, PS4, PC, Xbox 360, Xbox One - Trucos.com","isPartOf":{"@id":"https:\/\/trucos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/#primaryimage"},"image":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/resident-evil_600.jpg","datePublished":"2016-09-26T16:33:54+00:00","description":"Tous les trucs, astuces et \u00e9l\u00e9ments \u00e0 d\u00e9bloquer de Resident Evil HD","breadcrumb":{"@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/#primaryimage","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/resident-evil_600.jpg","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/resident-evil_600.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/trucos.com\/videojuegos\/trucos-resident-evil-hd-para-ps3-ps4-pc-xbox-360-xbox-one\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trucos.com\/"},{"@type":"ListItem","position":2,"name":"Trucos Resident Evil HD para PS3, PS4, PC, Xbox 360, Xbox One"}]},{"@type":"WebSite","@id":"https:\/\/trucos.com\/#website","url":"https:\/\/trucos.com\/","name":"Astuces.com","description":"Les meilleures astuces sur les jeux vid\u00e9o, la technologie et les t\u00e9l\u00e9phones portables","publisher":{"@id":"https:\/\/trucos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trucos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trucos.com\/#organization","name":"Astuces.com","url":"https:\/\/trucos.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","width":207,"height":68,"caption":"Trucos.com"},"image":{"@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trucoscom\/"]},{"@type":"Person","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536","name":"Redaction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","caption":"Redaccion"},"sameAs":["http:\/\/trucos.com"],"url":"https:\/\/trucos.com\/fr\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":0,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media\/471"}],"wp:attachment":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/categories?post=470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/tags?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}