{"id":736,"date":"2017-09-12T14:58:01","date_gmt":"2017-09-12T14:58:01","guid":{"rendered":"http:\/\/trucos.com\/uncategorized\/guia-destiny-2-planetas-personajes-y-tiendas\/"},"modified":"2023-08-03T12:15:30","modified_gmt":"2023-08-03T12:15:30","slug":"guider-destiny-2-planetes-et-personnages","status":"publish","type":"post","link":"https:\/\/trucos.com\/fr\/jeux-video\/guider-destiny-2-planetes-et-personnages\/","title":{"rendered":"Guide Destiny 2 \u2013 Plan\u00e8tes \u2013 Personnages et boutiques"},"content":{"rendered":"<p>Rejoignez l&#039;Avant-garde et aidez \u00e0 reprendre la ville et \u00e0 sauver le Voyageur de l&#039;impitoyable Dominus Ghaul de la L\u00e9gion Rouge de la Cabale. Pr\u00e9parez-vous au combat avec notre guide et ma\u00eetrisez tous les aspects de <a href=\"https:\/\/www.destinythegame.com\/es\/home\" title=\"Page officielle de Destiny 2\">Destin 2<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<table border=\"0\" cellpadding=\"1\" cellspacing=\"1\" style=\"width:100%\">\n<tbody>\n<tr>\n<td><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/guider-destiny-2-evenements-et-evenements-heroiques\/\" title=\"Guide Trucos.com Destiny 2 \u00c9v\u00e9nements h\u00e9ro\u00efques\">ET<\/a><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/guider-destiny-2-evenements-et-evenements-heroiques\/\" title=\"Guide Trucos.com Destiny 2 \u2013 \u00c9v\u00e9nements h\u00e9ro\u00efques\">Vents h\u00e9ro\u00efques<\/a><\/td>\n<td><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/astuces-destiny2-pour-ps4-pc-xbox-one\/\" title=\"Cheats.com Destiny 2 Astuces\">Destiny 2 Astuces<\/a><\/td>\n<td><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/destiny-2-guide-niveau-superieur\/\" title=\"Guide Tricos.com Destiny 2 Niveau sup\u00e9rieur\">Monter d&#039;un niveau<\/a><\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td><a href=\"http:\/\/trucos.com\/fr\/jeux-video\/guide-du-destin-2-activites-et-exploits-hebdomadaires\/\" title=\"tricks.com Destiny 2 Activit\u00e9s et exploits\">Activit\u00e9s et exploits<\/a><\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h2><img decoding=\"async\" alt=\"Destiny 2 \u2013 Carte totale\" src=\"\/media\/upload\/2017\/09\/13\/mapatotal.jpg\" style=\"width:100%\"><\/h2>\n<p>C&#039;est la carte finale de Destiny 2 avec tous ses emplacements d\u00e9bloqu\u00e9s, <strong>4 plan\u00e8tes \u00e0 explorer, 2 centres sociaux (La Villa et La Tour), L&#039;\u00c9preuve et les Assauts<\/strong>.&nbsp;<\/p>\n<p>Pour d\u00e9bloquer les plan\u00e8tes, nous devons simplement continuer les missions principales de l&#039;histoire. Ci-dessous nous vous laissons une description de <strong>toutes les plan\u00e8tes, zones sociales et personnages que nous allons rencontrer<\/strong> dans Destiny 2.<\/p>\n<h2>La Ville<\/h2>\n<p><img decoding=\"async\" alt=\"Destin 2 - Le Village\" src=\"\/media\/upload\/2017\/09\/13\/mapavilla.jpg\" style=\"width:100%\" title=\"Destin 2 - Le Village\"><\/p>\n<p>Apr\u00e8s la chute de la Ville, le centre o\u00f9 nous g\u00e9rons notre aventure est <strong>La Ville<\/strong>, tout comme la tour de Destiny, <strong>nous pouvons acc\u00e9der \u00e0 plusieurs personnages pour acheter, recevoir des r\u00e9compenses, acc\u00e9der \u00e0 des missions, sauvegarder du mat\u00e9riel<\/strong> etc. Apr\u00e8s avoir termin\u00e9 le prologue, nous acc\u00e9derons \u00e0 La Villa et de l\u00e0 commence notre aventure dans Destiny 2, dans cette zone nous pourrons parler \u00e0 plusieurs personnages :&nbsp;<\/p>\n<p><strong>Tess Everis\u00a0:&nbsp;<\/strong>&nbsp;marchande d&#039;objets \u00e9l\u00e9gants et tr\u00e8s recherch\u00e9s, ses r\u00e9compenses sont <strong>Shaders, modificateurs, shells de spectre<\/strong>, est \u00e9galement charg\u00e9 de d\u00e9crypter le<strong> Engrammes lumineux<\/strong>.<\/p>\n<p><strong>Seigneur Shaxx\u00a0:&nbsp;<\/strong>&nbsp;superviser le Creuset, <strong>multijoueur comp\u00e9titif<\/strong>. Terminez des matchs dans l&#039;\u00c9preuve et gagnez de la r\u00e9putation pour tester vos comp\u00e9tences et gagner des r\u00e9compenses.<\/p>\n<p><strong>Suraya Hawthorne\u00a0:<\/strong>&nbsp;un lien entre l&#039;humanit\u00e9 et les gardiens. Suraya offre un abri \u00e0 tous les survivants, elle est charg\u00e9e de nous confier des missions \u00e0 La Villa et de nous donner des r\u00e9compenses de clan.<\/p>\n<h3>Avant-garde Zavala, Ikora, Cayde-6<\/h3>\n<p><img decoding=\"async\" alt=\"Commandants de l&#039;avant-garde de Destiny 2\" src=\"\/media\/upload\/2017\/09\/12\/comandantes.jpg\" style=\"width:100%\" title=\"Commandants de l&#039;avant-garde de Destiny 2\"><\/p>\n<p><strong>Nous ne pouvons pas acc\u00e9der \u00e0 ces 3 personnages<\/strong> jusqu&#039;\u00e0 ce que nous ayons sauv\u00e9 Cayde-6 sur Nessus et convaincu Ikora sur Io, c&#039;est-\u00e0-dire jusqu&#039;\u00e0 ce que Io soit termin\u00e9. Une fois que nous avons rassembl\u00e9 les 3 gardiens nous pouvons les voir dans la Villa.<\/p>\n<ul>\n<li><strong>Zavala<\/strong> : nous d\u00e9bloque <strong>Raids et raids \u00e0 la tomb\u00e9e de la nuit<\/strong>.<\/li>\n<li><strong>Ikora<\/strong> : Cela nous d\u00e9verrouille<strong> D\u00e9fis<\/strong>.<\/li>\n<li><strong>Cayde 6<\/strong> : Cela nous d\u00e9verrouille <strong>Missions de patrouille<\/strong>.<\/li>\n<\/ul>\n<p><img decoding=\"async\" alt=\"Destiny 2 - Jeton d&#039;Avant-garde\" src=\"\/media\/upload\/2017\/09\/12\/fichavanguardia.jpg\" style=\"width:100%\" title=\"Destiny 2 - Jeton d&#039;Avant-garde\"><\/p>\n<p>Aussi pour accomplir leurs missions, ils nous donnent des objets \u00e0<strong> accro\u00eetre la r\u00e9putation<\/strong> avec chacun et recevez des r\u00e9compenses sous forme de <strong>Objets l\u00e9gendaires et exotiques<\/strong>. Plus tard, apr\u00e8s avoir termin\u00e9 le mode histoire, nous les verrons dans La Tour.&nbsp;<\/p>\n<h2>Plan\u00e8tes<\/h2>\n<p>Dans Destiny 2 nous visitons 4 plan\u00e8tes, la Terre, Titan, Nessus et Io, mais aussi dans chacune d&#039;elles nous avons un personnage avec lequel interagir, nous vous laissons d&#039;abord une description du caract\u00e8re de chaque plan\u00e8te puis la description des plan\u00e8tes.<\/p>\n<h3>Devrim Kay, Sloane, Failsafe, Asher Mir&nbsp;<\/h3>\n<p><img decoding=\"async\" alt=\"Personnages de Destin 2\" src=\"\/media\/upload\/2017\/09\/12\/npcs_planetas.jpg\" style=\"width:100%\" title=\"Personnages de Destin 2\"><\/p>\n<p>Outre les personnages que l&#039;on retrouve dans La Villa et plus tard dans la Tour, dans chacun des<strong> les 4 Zones<\/strong>&nbsp;que nous pouvons explorer,<strong> Terre, Titan, Nessus et Io<\/strong> nous avons <strong>un personnage qui nous donne des missions et des r\u00e9compenses<\/strong> accro\u00eetre la r\u00e9putation de ce personnage en effectuant des missions dans leurs r\u00e9gions.&nbsp;<\/p>\n<ul>\n<li><strong>Devrim Kay<\/strong> : Il a toujours \u00e9t\u00e9 un tireur d&#039;\u00e9lite gentleman, il d\u00e9fend pleinement sa position <strong>Zone morte europ\u00e9enne.<\/strong><\/li>\n<li><strong>Sloan<\/strong> : V\u00e9t\u00e9ran de nombreux champs de bataille, Sloane supervise le <strong>op\u00e9rations sur Titan<\/strong>.<\/li>\n<li><strong>S\u00e9curit\u00e9 int\u00e9gr\u00e9e<\/strong> : L&#039;intelligence artificielle \u00e0 s\u00e9curit\u00e9 int\u00e9gr\u00e9e est la <strong>guide des friches<\/strong> en proie \u00e0 Vex <strong>\u00e0 Nessos.<\/strong><\/li>\n<li><strong>Asher Mir<\/strong> : Marqu\u00e9 par sa rencontre avec les Vex, l&#039;irascible Asher Mir <strong>d\u00e9fendre Io <\/strong>pour l&#039;avant-garde et pour la science.<\/li>\n<\/ul>\n<h3>Zone morte europ\u00e9enne<\/h3>\n<p><img decoding=\"async\" alt=\"Destiny 2 - Zone morte europ\u00e9enne\" src=\"\/media\/upload\/2017\/09\/12\/zonamuerta.jpg\" style=\"width:100%\"><\/p>\n<p>La zone jouable de la Terre est la zone morte europ\u00e9enne, et non le cosmodrome de l&#039;original. C&#039;est un endroit vert et tr\u00e8s beau, qui, selon Bungie, est le plus grand qu&#039;ils aient construit. C&#039;est l\u00e0 que les Gardiens fuient apr\u00e8s que la Cabale ait attaqu\u00e9 la ville. En plus d&#039;\u00eatre l&#039;endroit o\u00f9 se trouve la Villa, c&#039;est \u00e9galement tr\u00e8s important car c&#039;est la zone o\u00f9 se trouve un grand fragment de voyageur et cela nous aidera \u00e0 activer les sous-classes de chaque gardien une fois que nous remplirons les conditions. La Terre est l&#039;endroit id\u00e9al pour commencer \u00e0 conna\u00eetre le jeu puisqu&#039;il s&#039;agit d&#039;une grande carte avec de nombreuses activit\u00e9s et \u00e9v\u00e9nements.<\/p>\n<h3>Titan<\/h3>\n<p><img decoding=\"async\" alt=\"Destin 2 - Titan\" src=\"\/media\/upload\/2017\/09\/12\/ttan.jpg\" style=\"width:100%\"><\/p>\n<p>Titan, l&#039;une des lunes de Saturne, est un vaste oc\u00e9an de m\u00e9thane dont les vagues de 40 m\u00e8tres s&#039;\u00e9crasent sur les \u00e9normes structures monolithiques construites par l&#039;humanit\u00e9 sur la plan\u00e8te.<strong> \u00e2ge d&#039;or<\/strong> avant que le Voyageur ne s&#039;endorme. C&#039;est ici que le Commandant Zavala, chef des Gardiens, va panser ses blessures apr\u00e8s l&#039;attaque de la Cabale. Il semble souffrir d&#039;une crise de foi apr\u00e8s avoir perdu la Derni\u00e8re Cit\u00e9. Zavala est d\u00e9termin\u00e9 \u00e0 riposter.<\/p>\n<h3>Nessos<\/h3>\n<p><img decoding=\"async\" alt=\"Destin 2 - Nessus\" src=\"\/media\/upload\/2017\/09\/12\/nessus.jpg\" style=\"width:100%\"><\/p>\n<p>Nessus est un plan\u00e9to\u00efde sous le contr\u00f4le des Vex, l&#039;une des races extraterrestres hostiles les plus int\u00e9ressantes de Destiny. Nessus est devenu presque enti\u00e8rement l&#039;un de ses mondes informatiques g\u00e9ants, mais sa surface conserve une beaut\u00e9 surnaturelle\u00a0: elle est compos\u00e9e d&#039;arbres rouges luxuriants, de rivi\u00e8res blanches et de canyons bas\u00e9s sur des plateaux r\u00e9els. Si le d\u00e9faut de Zavala est la haine de soi, Cayde-6 souffre d&#039;imprudence, il a r\u00e9ussi \u00e0 se faire pi\u00e9ger ici. Nessus raconte le sort d&#039;un vaisseau de colonie humaine arriv\u00e9 ici \u00e0 l&#039;\u00e2ge d&#039;or. Son IA \u00e0 bord, Failsafe, est son dernier survivant.<\/p>\n<h3>Io<\/h3>\n<p><img decoding=\"async\" alt=\"Destin 2 - Io\" src=\"\/media\/upload\/2017\/09\/12\/io.jpg\" style=\"width:100%\"><\/p>\n<p>Lune sulfurique de Jupiter, c&#039;est jusqu&#039;\u00e0 pr\u00e9sent l&#039;endroit le plus \u00e9loign\u00e9 de la Terre dans Destiny, et le dernier endroit que la Lumi\u00e8re du Voyageur a touch\u00e9 avant l&#039;Effondrement. C\u2019est donc un monde myst\u00e9rieux, sacr\u00e9 pour les Gardiens, et pour les Sorciers en particulier. Ikora Rey, apr\u00e8s la perte de la Tour, se retire \u00e0 Io et vous devrez venir la persuader de revenir.&nbsp;<\/p>\n<h2>La tour<\/h2>\n<p><img decoding=\"async\" alt=\"Destiny 2 - La Tour\" src=\"\/media\/upload\/2017\/09\/13\/latorre.jpg\" style=\"width:100%\" title=\"Destiny 2 - La Tour\"><\/p>\n<p>Une fois le mode campagne termin\u00e9 et de retour en ville, le centre social de La Torre appara\u00eet \u00e0 nouveau, ce n&#039;est pas exactement le m\u00eame que celui de Destiny 1, mais il est tr\u00e8s similaire et tout est plus concentr\u00e9. Dans La Tour on retrouve pratiquement tous les personnages que l&#039;on rencontre dans La Villa \u00e0 l&#039;exception du cryptarque Tyra Karn, on verra Hawthorne, les Gardiens Zavala, Ikora et Cayde-6, Tess Everis et tout ce qui touche au Creuset, en plus On retrouve de nouveaux personnages dans ce lieu que nous vous pr\u00e9sentons ci-dessous :<\/p>\n<p><strong>Ma\u00eetre Rahol :&nbsp;<\/strong>&nbsp;repr\u00e9sentant de la cryptarchie, d\u00e9chiffre les engrammes et recherche les tr\u00e9sors du pass\u00e9 de l&#039;humanit\u00e9. Donnez-lui les engrammes trouv\u00e9s pour recevoir des \u00e9quipements puissants et d&#039;autres objets.<\/p>\n<p><strong>Kadi 55-30\u00a0:&nbsp;<\/strong>&nbsp;Les andro\u00efdes administrateurs surveillent avec diligence les livraisons, les messages et les objets perdus. Visitez-le de temps en temps car il a parfois des objets pour vous.<\/p>\n<p><strong>Banshee-44\u00a0:<\/strong>&nbsp;Ma\u00eetre Armurier de la Tour, n&#039;offre aux Gardiens que le meilleur du meilleur. En d\u00e9montant les armes et l&#039;\u00e9quipement, nous obtenons des mat\u00e9riaux de forgeron d&#039;armes, que nous livrons \u00e0 cet armurier pour augmenter le niveau de faction et recevoir des r\u00e9compenses.<\/p>\n<p><strong>Amanda Holliday \u2013 <\/strong>&nbsp;Il g\u00e8re le Hangar comme un moteur bien huil\u00e9. Amanda nous vend les navires et v\u00e9hicules colibris. \u00c0 la fin de la campagne, vous recevrez un colibri si vous allez le visiter.<\/p>\n<p><img decoding=\"async\" alt=\"Destiny 2 \u2013 Carte de la tour\" src=\"\/media\/upload\/2017\/09\/13\/mapatorre_ZKsa9UX.jpg\" style=\"width:100%\" title=\"Destiny 2 \u2013 Carte de la tour\"><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Conna\u00eetre toutes les plan\u00e8tes et personnages de Destiny 2, La Villa et leurs fonctions, tous les emplacements de La Torre, Zavala, Cayde-6, Ikora<\/p>","protected":false},"author":2,"featured_media":735,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[70],"class_list":["post-736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videojuegos","tag-ocio"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gu\u00eda Destiny 2 - Planetas - Personajes y Tiendas - Trucos.com<\/title>\n<meta name=\"description\" content=\"Conoce todos los planetas y personajes de Destiny 2, La Villa y sus funciones, todas las localizaciones de La Torre, Zavala, Cayde-6, Ikora\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trucos.com\/fr\/jeux-video\/guider-destiny-2-planetes-et-personnages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00eda Destiny 2 - Planetas - Personajes y Tiendas - Trucos.com\" \/>\n<meta property=\"og:description\" content=\"Conoce todos los planetas y personajes de Destiny 2, La Villa y sus funciones, todas las localizaciones de La Torre, Zavala, Cayde-6, Ikora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trucos.com\/fr\/jeux-video\/guider-destiny-2-planetes-et-personnages\/\" \/>\n<meta property=\"og:site_name\" content=\"Trucos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trucoscom\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-12T14:58:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-03T12:15:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Destiny2_600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide Destiny 2 - Plan\u00e8tes - Personnages et boutiques - Trucos.com","description":"Conna\u00eetre toutes les plan\u00e8tes et personnages de Destiny 2, La Villa et leurs fonctions, tous les emplacements de La Torre, Zavala, Cayde-6, Ikora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trucos.com\/fr\/jeux-video\/guider-destiny-2-planetes-et-personnages\/","og_locale":"fr_FR","og_type":"article","og_title":"Gu\u00eda Destiny 2 - Planetas - Personajes y Tiendas - Trucos.com","og_description":"Conoce todos los planetas y personajes de Destiny 2, La Villa y sus funciones, todas las localizaciones de La Torre, Zavala, Cayde-6, Ikora","og_url":"https:\/\/trucos.com\/fr\/jeux-video\/guider-destiny-2-planetes-et-personnages\/","og_site_name":"Trucos.com","article_publisher":"https:\/\/www.facebook.com\/trucoscom\/","article_published_time":"2017-09-12T14:58:01+00:00","article_modified_time":"2023-08-03T12:15:30+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Destiny2_600.jpg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redaccion","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/#article","isPartOf":{"@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/"},"author":{"name":"Redaccion","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536"},"headline":"Gu\u00eda Destiny 2 &#8211; Planetas &#8211; Personajes y Tiendas","datePublished":"2017-09-12T14:58:01+00:00","dateModified":"2023-08-03T12:15:30+00:00","mainEntityOfPage":{"@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/"},"wordCount":1236,"publisher":{"@id":"https:\/\/trucos.com\/#organization"},"image":{"@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Destiny2_600.jpg","keywords":["Ocio"],"articleSection":["Videojuegos"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/","url":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/","name":"Guide Destiny 2 - Plan\u00e8tes - Personnages et boutiques - Trucos.com","isPartOf":{"@id":"https:\/\/trucos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/#primaryimage"},"image":{"@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/#primaryimage"},"thumbnailUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Destiny2_600.jpg","datePublished":"2017-09-12T14:58:01+00:00","dateModified":"2023-08-03T12:15:30+00:00","description":"Conna\u00eetre toutes les plan\u00e8tes et personnages de Destiny 2, La Villa et leurs fonctions, tous les emplacements de La Torre, Zavala, Cayde-6, Ikora","breadcrumb":{"@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/#primaryimage","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Destiny2_600.jpg","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/Destiny2_600.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/trucos.com\/videojuegos\/guia-destiny-2-planetas-y-personajes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trucos.com\/"},{"@type":"ListItem","position":2,"name":"Gu\u00eda Destiny 2 &#8211; Planetas &#8211; Personajes y Tiendas"}]},{"@type":"WebSite","@id":"https:\/\/trucos.com\/#website","url":"https:\/\/trucos.com\/","name":"Astuces.com","description":"Les meilleures astuces sur les jeux vid\u00e9o, la technologie et les t\u00e9l\u00e9phones portables","publisher":{"@id":"https:\/\/trucos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trucos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trucos.com\/#organization","name":"Astuces.com","url":"https:\/\/trucos.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/","url":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","contentUrl":"https:\/\/trucos.com\/wp-content\/uploads\/2023\/06\/trucoscomlogo.png","width":207,"height":68,"caption":"Trucos.com"},"image":{"@id":"https:\/\/trucos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trucoscom\/"]},{"@type":"Person","@id":"https:\/\/trucos.com\/#\/schema\/person\/a435f425aecd84e1df6f98ccee7ce536","name":"Redaction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9294dcdc49d94ba92a2933c1c65d27c01fed9c237bbd5f6c305ee54ff52f55b?s=96&d=mm&r=g","caption":"Redaccion"},"sameAs":["http:\/\/trucos.com"],"url":"https:\/\/trucos.com\/fr\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/comments?post=736"}],"version-history":[{"count":1,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/736\/revisions"}],"predecessor-version":[{"id":3489,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/posts\/736\/revisions\/3489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media\/735"}],"wp:attachment":[{"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/media?parent=736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/categories?post=736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trucos.com\/fr\/wp-json\/wp\/v2\/tags?post=736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}